{"id":273,"count":0,"description":"","link":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/tag\/guess-green\/","name":"Guess Green","slug":"guess-green","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Guess Green Archives - Valley Girl<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guess Green Archives - Valley Girl\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/tag\/guess-green\/\" \/>\n<meta property=\"og:site_name\" content=\"Valley Girl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/tag\\\/guess-green\\\/\",\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/tag\\\/guess-green\\\/\",\"name\":\"Guess Green Archives - Valley Girl\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/tag\\\/guess-green\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/tag\\\/guess-green\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Guess Green\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#website\",\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/\",\"name\":\"Valley Girl\",\"description\":\"A blog for Phoenix area women\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#organization\",\"name\":\"AZFoothills.com LLC\",\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/25072512\\\/apple-touch-icon.jpg\",\"contentUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/25072512\\\/apple-touch-icon.jpg\",\"width\":180,\"height\":180,\"caption\":\"AZFoothills.com LLC\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Guess Green Archives - Valley Girl","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Guess Green Archives - Valley Girl","og_url":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/tag\/guess-green\/","og_site_name":"Valley Girl","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/tag\/guess-green\/","url":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/tag\/guess-green\/","name":"Guess Green Archives - Valley Girl","isPartOf":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#website"},"breadcrumb":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/tag\/guess-green\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/tag\/guess-green\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/"},{"@type":"ListItem","position":2,"name":"Guess Green"}]},{"@type":"WebSite","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#website","url":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/","name":"Valley Girl","description":"A blog for Phoenix area women","publisher":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#organization","name":"AZFoothills.com LLC","url":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#\/schema\/logo\/image\/","url":"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2021\/06\/25072512\/apple-touch-icon.jpg","contentUrl":"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2021\/06\/25072512\/apple-touch-icon.jpg","width":180,"height":180,"caption":"AZFoothills.com LLC"},"image":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/tags\/273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/posts?tags=273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}