{"id":27573,"date":"2022-07-28T02:57:30","date_gmt":"2022-07-28T09:57:30","guid":{"rendered":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/?p=27573"},"modified":"2022-07-29T08:05:45","modified_gmt":"2022-07-29T15:05:45","slug":"squeeze-new-massage-experience-by-drybar-is-coming-to-scottsdale","status":"publish","type":"post","link":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/fitness-health\/squeeze-new-massage-experience-by-drybar-is-coming-to-scottsdale\/","title":{"rendered":"Squeeze, a New Massage Experience by Drybar, is Coming to Scottsdale"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2022\/07\/28025626\/Squeeze-Storefront195.jpg\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"1024\"  height=\"726\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  alt=\"\"  class=\"wp-image-27576 pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"  data-pk-src=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2022\/07\/28025626\/Squeeze-Storefront195-1024x726.jpg\"  data-pk-srcset=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2022\/07\/28025626\/Squeeze-Storefront195-1024x726.jpg 1024w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2022\/07\/28025626\/Squeeze-Storefront195-300x213.jpg 300w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2022\/07\/28025626\/Squeeze-Storefront195-768x545.jpg 768w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2022\/07\/28025626\/Squeeze-Storefront195-1536x1089.jpg 1536w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2022\/07\/28025626\/Squeeze-Storefront195-2048x1452.jpg 2048w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2022\/07\/28025626\/Squeeze-Storefront195-380x269.jpg 380w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2022\/07\/28025626\/Squeeze-Storefront195-800x567.jpg 800w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2022\/07\/28025626\/Squeeze-Storefront195-1160x822.jpg 1160w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2022\/07\/28025626\/Squeeze-Storefront195-80x58.jpg 80w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2022\/07\/28025626\/Squeeze-Storefront195.jpg 2416w\" ><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Squeeze, a premier massage franchise started by the founders of Drybar, is soon coming to Scottsdale.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Branded as a way better massage experience, Squeeze offers personalized massages, a stress-free booking app and community-benefitting memberships. The Scottsdale massage boutique will be the brand\u2019s second location since opening in Los Angeles.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Located at 4513 N Scottsdale Rd Suite 112, across from Apple and next to Sprinkles Cupcakes, the 3,200-square-foot space will hold 11 rooms to provide customers with a seamless, customizable and one-of-a-kind massage experience.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cOur vision at Squeeze is to transform communities for good so we\u2019ve created a relaxing and hassle-free experience for our guests, as well as a positive and uplifting space for our team to come to work every day,\u201d says Squeeze Co-Founder and CEO Brittany Driscoll.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">At Squeeze, every element of the guest experience is curated to be convenient and personalized. Each massage is tailored to the customer\u2019s liking, including pressure, music and lighting, as well as the choice of deep tissue, heat therapy, aromatherapy and percussion therapy at no extra cost. A \u201cready\u201d button lets the therapist know when to enter the room to begin the massage.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Through the Squeeze app and website, guests can save their personalized preferences for therapists to review prior to appointments, as well as book, pay, tip, rate and review, allowing them to walk in and figuratively \u201cfloat out\u201d after their massage.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In addition to providing guests with positive massage experiences, Squeeze, now with over 37 locations in development across the country, continues to keep the success of existing and future operating partners in mind to create a better franchise experience.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The company is also committed to \u201cThe Feel-Good Revolution,\u201d a goal to not only make people feel good but do good as well. Therefore, for every membership sold, Squeeze is helping to provide a day of canine support to a person with a disability through Canine Companions, the nation\u2019s leading dog service provider.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Little things are big things here at Squeeze\u2014a philosophy that has shone through every facet of our experience since joining this new family,\u201d says Squeeze Scottsdale Operating Partners Andrew Nicoll and Sam Lewis. \u201cEvery detail of the establishment has been intentionally crafted with the guest in mind, and every detail of the business model has been crafted with the franchisee in mind. The Scottsdale community is gaining a business and brand who is well on their way to creating The Feel-Good Revolution and we are overjoyed to be a part of it.&#8221;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">For more information on Squeeze memberships and pricing, visit <a href=\"https:\/\/www.squeezemassage.com\" target=\"_blank\" rel=\"noreferrer noopener\">squeezemassage.com<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"Squeeze will offer personalized massages, a stress-free booking app and community-benefitting memberships.\n","protected":false},"author":28,"featured_media":27576,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[74],"tags":[8566,13370,13368,13369],"class_list":["post-27573","post","type-post","status-publish","format-standard","has-post-thumbnail","category-fitness-health","tag-featured","tag-new-openings","tag-squeeze-massage","tag-squeeze-scottsdale","cs-entry","cs-video-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Squeeze, a New Massage Experience by Drybar, is Coming to Scottsdale<\/title>\n<meta name=\"description\" content=\"Squeeze will offer personalized massages, a stress-free booking app and community-benefitting memberships.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/fitness-health\/squeeze-new-massage-experience-by-drybar-is-coming-to-scottsdale\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Squeeze, a New Massage Experience by Drybar, is Coming to Scottsdale\" \/>\n<meta property=\"og:description\" content=\"Squeeze will offer personalized massages, a stress-free booking app and community-benefitting memberships.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/fitness-health\/squeeze-new-massage-experience-by-drybar-is-coming-to-scottsdale\/\" \/>\n<meta property=\"og:site_name\" content=\"Valley Girl\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-28T09:57:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-29T15:05:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2022\/07\/28025626\/Squeeze-Storefront195-1024x726.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"726\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Savannah Leedy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/fitness-health\\\/squeeze-new-massage-experience-by-drybar-is-coming-to-scottsdale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/fitness-health\\\/squeeze-new-massage-experience-by-drybar-is-coming-to-scottsdale\\\/\"},\"author\":{\"name\":\"Savannah Leedy\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#\\\/schema\\\/person\\\/11094707ae6fae5ee572b4b43cce6c6b\"},\"headline\":\"Squeeze, a New Massage Experience by Drybar, is Coming to Scottsdale\",\"datePublished\":\"2022-07-28T09:57:30+00:00\",\"dateModified\":\"2022-07-29T15:05:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/fitness-health\\\/squeeze-new-massage-experience-by-drybar-is-coming-to-scottsdale\\\/\"},\"wordCount\":443,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/fitness-health\\\/squeeze-new-massage-experience-by-drybar-is-coming-to-scottsdale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/28025626\\\/Squeeze-Storefront195.jpg\",\"keywords\":[\"featured\",\"new openings\",\"Squeeze massage\",\"Squeeze Scottsdale\"],\"articleSection\":[\"Fitness &amp; Health\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/fitness-health\\\/squeeze-new-massage-experience-by-drybar-is-coming-to-scottsdale\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/fitness-health\\\/squeeze-new-massage-experience-by-drybar-is-coming-to-scottsdale\\\/\",\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/fitness-health\\\/squeeze-new-massage-experience-by-drybar-is-coming-to-scottsdale\\\/\",\"name\":\"Squeeze, a New Massage Experience by Drybar, is Coming to Scottsdale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/fitness-health\\\/squeeze-new-massage-experience-by-drybar-is-coming-to-scottsdale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/fitness-health\\\/squeeze-new-massage-experience-by-drybar-is-coming-to-scottsdale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/28025626\\\/Squeeze-Storefront195.jpg\",\"datePublished\":\"2022-07-28T09:57:30+00:00\",\"dateModified\":\"2022-07-29T15:05:45+00:00\",\"description\":\"Squeeze will offer personalized massages, a stress-free booking app and community-benefitting memberships.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/fitness-health\\\/squeeze-new-massage-experience-by-drybar-is-coming-to-scottsdale\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/fitness-health\\\/squeeze-new-massage-experience-by-drybar-is-coming-to-scottsdale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/fitness-health\\\/squeeze-new-massage-experience-by-drybar-is-coming-to-scottsdale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/28025626\\\/Squeeze-Storefront195.jpg\",\"contentUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/28025626\\\/Squeeze-Storefront195.jpg\",\"width\":2416,\"height\":1713},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/fitness-health\\\/squeeze-new-massage-experience-by-drybar-is-coming-to-scottsdale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Squeeze, a New Massage Experience by Drybar, is Coming to Scottsdale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#website\",\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/\",\"name\":\"Valley Girl\",\"description\":\"A blog for Phoenix area women\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#organization\",\"name\":\"AZFoothills.com LLC\",\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/25072512\\\/apple-touch-icon.jpg\",\"contentUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/25072512\\\/apple-touch-icon.jpg\",\"width\":180,\"height\":180,\"caption\":\"AZFoothills.com LLC\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#\\\/schema\\\/person\\\/11094707ae6fae5ee572b4b43cce6c6b\",\"name\":\"Savannah Leedy\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/818d93bd5f475efc5dce224bbf23083f75eb1c6b09aad56b12d3640bbf6986d9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/818d93bd5f475efc5dce224bbf23083f75eb1c6b09aad56b12d3640bbf6986d9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/818d93bd5f475efc5dce224bbf23083f75eb1c6b09aad56b12d3640bbf6986d9?s=96&d=mm&r=g\",\"caption\":\"Savannah Leedy\"},\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/author\\\/savannah\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Squeeze, a New Massage Experience by Drybar, is Coming to Scottsdale","description":"Squeeze will offer personalized massages, a stress-free booking app and community-benefitting memberships.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/fitness-health\/squeeze-new-massage-experience-by-drybar-is-coming-to-scottsdale\/","og_locale":"en_US","og_type":"article","og_title":"Squeeze, a New Massage Experience by Drybar, is Coming to Scottsdale","og_description":"Squeeze will offer personalized massages, a stress-free booking app and community-benefitting memberships.","og_url":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/fitness-health\/squeeze-new-massage-experience-by-drybar-is-coming-to-scottsdale\/","og_site_name":"Valley Girl","article_published_time":"2022-07-28T09:57:30+00:00","article_modified_time":"2022-07-29T15:05:45+00:00","og_image":[{"width":1024,"height":726,"url":"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2022\/07\/28025626\/Squeeze-Storefront195-1024x726.jpg","type":"image\/jpeg"}],"author":"Savannah Leedy","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/fitness-health\/squeeze-new-massage-experience-by-drybar-is-coming-to-scottsdale\/#article","isPartOf":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/fitness-health\/squeeze-new-massage-experience-by-drybar-is-coming-to-scottsdale\/"},"author":{"name":"Savannah Leedy","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#\/schema\/person\/11094707ae6fae5ee572b4b43cce6c6b"},"headline":"Squeeze, a New Massage Experience by Drybar, is Coming to Scottsdale","datePublished":"2022-07-28T09:57:30+00:00","dateModified":"2022-07-29T15:05:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/fitness-health\/squeeze-new-massage-experience-by-drybar-is-coming-to-scottsdale\/"},"wordCount":443,"commentCount":0,"publisher":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#organization"},"image":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/fitness-health\/squeeze-new-massage-experience-by-drybar-is-coming-to-scottsdale\/#primaryimage"},"thumbnailUrl":"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2022\/07\/28025626\/Squeeze-Storefront195.jpg","keywords":["featured","new openings","Squeeze massage","Squeeze Scottsdale"],"articleSection":["Fitness &amp; Health"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/fitness-health\/squeeze-new-massage-experience-by-drybar-is-coming-to-scottsdale\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/fitness-health\/squeeze-new-massage-experience-by-drybar-is-coming-to-scottsdale\/","url":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/fitness-health\/squeeze-new-massage-experience-by-drybar-is-coming-to-scottsdale\/","name":"Squeeze, a New Massage Experience by Drybar, is Coming to Scottsdale","isPartOf":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/fitness-health\/squeeze-new-massage-experience-by-drybar-is-coming-to-scottsdale\/#primaryimage"},"image":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/fitness-health\/squeeze-new-massage-experience-by-drybar-is-coming-to-scottsdale\/#primaryimage"},"thumbnailUrl":"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2022\/07\/28025626\/Squeeze-Storefront195.jpg","datePublished":"2022-07-28T09:57:30+00:00","dateModified":"2022-07-29T15:05:45+00:00","description":"Squeeze will offer personalized massages, a stress-free booking app and community-benefitting memberships.","breadcrumb":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/fitness-health\/squeeze-new-massage-experience-by-drybar-is-coming-to-scottsdale\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/fitness-health\/squeeze-new-massage-experience-by-drybar-is-coming-to-scottsdale\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/fitness-health\/squeeze-new-massage-experience-by-drybar-is-coming-to-scottsdale\/#primaryimage","url":"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2022\/07\/28025626\/Squeeze-Storefront195.jpg","contentUrl":"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2022\/07\/28025626\/Squeeze-Storefront195.jpg","width":2416,"height":1713},{"@type":"BreadcrumbList","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/fitness-health\/squeeze-new-massage-experience-by-drybar-is-coming-to-scottsdale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/"},{"@type":"ListItem","position":2,"name":"Squeeze, a New Massage Experience by Drybar, is Coming to Scottsdale"}]},{"@type":"WebSite","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#website","url":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/","name":"Valley Girl","description":"A blog for Phoenix area women","publisher":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#organization","name":"AZFoothills.com LLC","url":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#\/schema\/logo\/image\/","url":"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2021\/06\/25072512\/apple-touch-icon.jpg","contentUrl":"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2021\/06\/25072512\/apple-touch-icon.jpg","width":180,"height":180,"caption":"AZFoothills.com LLC"},"image":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#\/schema\/person\/11094707ae6fae5ee572b4b43cce6c6b","name":"Savannah Leedy","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/818d93bd5f475efc5dce224bbf23083f75eb1c6b09aad56b12d3640bbf6986d9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/818d93bd5f475efc5dce224bbf23083f75eb1c6b09aad56b12d3640bbf6986d9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/818d93bd5f475efc5dce224bbf23083f75eb1c6b09aad56b12d3640bbf6986d9?s=96&d=mm&r=g","caption":"Savannah Leedy"},"url":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/author\/savannah\/"}]}},"_links":{"self":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/posts\/27573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/comments?post=27573"}],"version-history":[{"count":5,"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/posts\/27573\/revisions"}],"predecessor-version":[{"id":27579,"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/posts\/27573\/revisions\/27579"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/media\/27576"}],"wp:attachment":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/media?parent=27573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/categories?post=27573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/tags?post=27573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}