{"id":21105,"date":"2016-01-07T12:35:14","date_gmt":"2016-01-07T19:35:14","guid":{"rendered":"http:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/?p=21105"},"modified":"2016-01-07T12:35:32","modified_gmt":"2016-01-07T19:35:32","slug":"most-glamorous-peoples-choice-awards-red-carpet-looks","status":"publish","type":"post","link":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/most-glamorous-peoples-choice-awards-red-carpet-looks\/","title":{"rendered":"Most Glamorous People&#8217;s Choice Awards Red Carpet Looks"},"content":{"rendered":"<figure id=\"attachment_21108\" aria-describedby=\"caption-attachment-21108\" style=\"width: 618px\" class=\"wp-caption aligncenter\"><img  loading=\"lazy\"  decoding=\"async\"  class=\" wp-image-21108 pk-lazyload\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  alt=\"Image via In Touch Weekly\"  width=\"618\"  height=\"412\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 618px) 100vw, 618px\"  data-pk-src=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042520\/julianne-hough-peoples-choice-awards-750x500.jpg\"  data-pk-srcset=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042520\/julianne-hough-peoples-choice-awards-750x500.jpg 750w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042520\/julianne-hough-peoples-choice-awards-300x200.jpg 300w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042520\/julianne-hough-peoples-choice-awards-1024x683.jpg 1024w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042520\/julianne-hough-peoples-choice-awards-768x512.jpg 768w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042520\/julianne-hough-peoples-choice-awards-380x253.jpg 380w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042520\/julianne-hough-peoples-choice-awards-800x533.jpg 800w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042520\/julianne-hough-peoples-choice-awards-1160x773.jpg 1160w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042520\/julianne-hough-peoples-choice-awards-80x53.jpg 80w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042520\/julianne-hough-peoples-choice-awards-620x413.jpg 620w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042520\/julianne-hough-peoples-choice-awards-850x567.jpg 850w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042520\/julianne-hough-peoples-choice-awards.jpg 1200w\" ><figcaption id=\"caption-attachment-21108\" class=\"wp-caption-text\">Image via In Touch Weekly<\/figcaption><\/figure>\n<p>The 2016 People\u2019s Choice Awards showcased some of the best legs, low-cut necklines and eye-catching gowns of any red carpets. \u00a0Featured below are the best dressed celebrities at the 2016 PCA\u2019s. \u00a0These women certainly stole the spotlight!<\/p>\n<p><strong>Priyanka Chopa\u00a0<\/strong><\/p>\n<figure id=\"attachment_21106\" aria-describedby=\"caption-attachment-21106\" style=\"width: 441px\" class=\"wp-caption aligncenter\"><img  loading=\"lazy\"  decoding=\"async\"  class=\" wp-image-21106 pk-lazyload\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  alt=\"Image via Zimbio\"  width=\"441\"  height=\"657\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 441px) 100vw, 441px\"  data-pk-src=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042511\/PeopleChoiceAwards2016RedCarpetZbyQde61tzvl.jpg\"  data-pk-srcset=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042511\/PeopleChoiceAwards2016RedCarpetZbyQde61tzvl.jpg 403w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042511\/PeopleChoiceAwards2016RedCarpetZbyQde61tzvl-202x300.jpg 202w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042511\/PeopleChoiceAwards2016RedCarpetZbyQde61tzvl-380x566.jpg 380w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042511\/PeopleChoiceAwards2016RedCarpetZbyQde61tzvl-80x119.jpg 80w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042511\/PeopleChoiceAwards2016RedCarpetZbyQde61tzvl-54x80.jpg 54w\" ><figcaption id=\"caption-attachment-21106\" class=\"wp-caption-text\">Image via Zimbio<\/figcaption><\/figure>\n<p><strong>Kate Hudson<\/strong><\/p>\n<figure id=\"attachment_21107\" aria-describedby=\"caption-attachment-21107\" style=\"width: 504px\" class=\"wp-caption aligncenter\"><img  loading=\"lazy\"  decoding=\"async\"  class=\"wp-image-21107 pk-lazyload\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  alt=\"kate-hudson\"  width=\"504\"  height=\"674\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 504px) 100vw, 504px\"  data-pk-src=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042515\/kate-hudson-750x1002.jpg\"  data-pk-srcset=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042515\/kate-hudson-750x1002.jpg 750w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042515\/kate-hudson-225x300.jpg 225w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042515\/kate-hudson-767x1024.jpg 767w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042515\/kate-hudson-768x1026.jpg 768w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042515\/kate-hudson-1150x1536.jpg 1150w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042515\/kate-hudson-380x508.jpg 380w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042515\/kate-hudson-800x1069.jpg 800w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042515\/kate-hudson-1160x1550.jpg 1160w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042515\/kate-hudson-80x107.jpg 80w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042515\/kate-hudson-60x80.jpg 60w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042515\/kate-hudson-620x828.jpg 620w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042515\/kate-hudson-850x1135.jpg 850w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042515\/kate-hudson.jpg 1200w\" ><figcaption id=\"caption-attachment-21107\" class=\"wp-caption-text\">New York Daily News<\/figcaption><\/figure>\n<p><strong>Lea Michelle<\/strong><\/p>\n<figure id=\"attachment_21109\" aria-describedby=\"caption-attachment-21109\" style=\"width: 425px\" class=\"wp-caption aligncenter\"><img  loading=\"lazy\"  decoding=\"async\"  class=\"size-full wp-image-21109 pk-lqip pk-lazyload\"  src=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042523\/425_lea_michele_503701658-80x120.jpg\"  alt=\"LOS ANGELES, CA - JANUARY 06: Actress Lea Michele poses in the press room during the People&#039;s Choice Awards 2016 at Microsoft Theater on January 6, 2016 in Los Angeles, California. (Photo by Jason Merritt\/Getty Images)\"  width=\"425\"  height=\"638\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 425px) 100vw, 425px\"  data-pk-src=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042523\/425_lea_michele_503701658.jpg\"  data-pk-srcset=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042523\/425_lea_michele_503701658.jpg 425w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042523\/425_lea_michele_503701658-200x300.jpg 200w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042523\/425_lea_michele_503701658-380x570.jpg 380w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042523\/425_lea_michele_503701658-80x120.jpg 80w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042523\/425_lea_michele_503701658-53x80.jpg 53w\" ><figcaption id=\"caption-attachment-21109\" class=\"wp-caption-text\">LOS ANGELES, CA \u2013 JANUARY 06: Actress Lea Michele poses in the press room during the People\u2019s Choice Awards 2016 at Microsoft Theater on January 6, 2016 in Los Angeles, California. (Photo by Jason Merritt\/Getty Images)<\/figcaption><\/figure>\n<p>Julianne Hough<\/p>\n<figure id=\"attachment_21111\" aria-describedby=\"caption-attachment-21111\" style=\"width: 584px\" class=\"wp-caption aligncenter\"><img  loading=\"lazy\"  decoding=\"async\"  class=\" wp-image-21111 pk-lazyload\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  alt=\"Image Via The Indian Express\"  width=\"584\"  height=\"819\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 584px) 100vw, 584px\"  data-pk-src=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042531\/juliannehough-reuters-730x1024.jpg\"  data-pk-srcset=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042531\/juliannehough-reuters-730x1024.jpg 730w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042531\/juliannehough-reuters-214x300.jpg 214w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042531\/juliannehough-reuters-768x1077.jpg 768w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042531\/juliannehough-reuters-380x533.jpg 380w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042531\/juliannehough-reuters-800x1122.jpg 800w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042531\/juliannehough-reuters-80x112.jpg 80w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042531\/juliannehough-reuters-57x80.jpg 57w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042531\/juliannehough-reuters-620x870.jpg 620w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042531\/juliannehough-reuters.jpg 820w\" ><figcaption id=\"caption-attachment-21111\" class=\"wp-caption-text\">Image Via The Indian Express<\/figcaption><\/figure>\n<p><strong>Claire Danes\u00a0<\/strong><\/p>\n<figure id=\"attachment_21112\" aria-describedby=\"caption-attachment-21112\" style=\"width: 581px\" class=\"wp-caption aligncenter\"><img  loading=\"lazy\"  decoding=\"async\"  class=\" wp-image-21112 pk-lazyload\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  alt=\"Image Via The Indian Express\"  width=\"581\"  height=\"899\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 581px) 100vw, 581px\"  data-pk-src=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042534\/clairedanes-reuters-662x1024.jpg\"  data-pk-srcset=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042534\/clairedanes-reuters-662x1024.jpg 662w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042534\/clairedanes-reuters-194x300.jpg 194w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042534\/clairedanes-reuters-768x1188.jpg 768w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042534\/clairedanes-reuters-380x588.jpg 380w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042534\/clairedanes-reuters-800x1237.jpg 800w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042534\/clairedanes-reuters-80x124.jpg 80w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042534\/clairedanes-reuters-52x80.jpg 52w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042534\/clairedanes-reuters-620x959.jpg 620w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042534\/clairedanes-reuters.jpg 820w\" ><figcaption id=\"caption-attachment-21112\" class=\"wp-caption-text\">Image Via The Indian Express<\/figcaption><\/figure>\n<p><strong>Vanessa Hudgens<\/strong><\/p>\n<figure id=\"attachment_21110\" aria-describedby=\"caption-attachment-21110\" style=\"width: 581px\" class=\"wp-caption aligncenter\"><img  loading=\"lazy\"  decoding=\"async\"  class=\" wp-image-21110 pk-lazyload\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  alt=\"Image Via The Indian Express\"  width=\"581\"  height=\"935\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 581px) 100vw, 581px\"  data-pk-src=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042527\/vanessahudgen-ap-636x1024.jpg\"  data-pk-srcset=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042527\/vanessahudgen-ap-636x1024.jpg 636w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042527\/vanessahudgen-ap-186x300.jpg 186w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042527\/vanessahudgen-ap-768x1237.jpg 768w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042527\/vanessahudgen-ap-380x612.jpg 380w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042527\/vanessahudgen-ap-800x1289.jpg 800w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042527\/vanessahudgen-ap-80x129.jpg 80w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042527\/vanessahudgen-ap-50x80.jpg 50w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042527\/vanessahudgen-ap-620x999.jpg 620w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042527\/vanessahudgen-ap.jpg 820w\" ><figcaption id=\"caption-attachment-21110\" class=\"wp-caption-text\">Image Via The Indian Express<\/figcaption><\/figure>\n<p><strong>Christina Milian<\/strong><\/p>\n<figure id=\"attachment_21114\" aria-describedby=\"caption-attachment-21114\" style=\"width: 597px\" class=\"wp-caption aligncenter\"><img  loading=\"lazy\"  decoding=\"async\"  class=\" wp-image-21114 pk-lazyload\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  alt=\"Image Via The Indian Express\"  width=\"597\"  height=\"673\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 597px) 100vw, 597px\"  data-pk-src=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042538\/christinamilian-750x846.jpg\"  data-pk-srcset=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042538\/christinamilian-750x846.jpg 750w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042538\/christinamilian-266x300.jpg 266w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042538\/christinamilian-768x866.jpg 768w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042538\/christinamilian-380x429.jpg 380w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042538\/christinamilian-800x902.jpg 800w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042538\/christinamilian-80x90.jpg 80w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042538\/christinamilian-71x80.jpg 71w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042538\/christinamilian-620x699.jpg 620w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042538\/christinamilian.jpg 820w\" ><figcaption id=\"caption-attachment-21114\" class=\"wp-caption-text\">Image Via The Indian Express<\/figcaption><\/figure>\n<p><strong>Shay Mitchell of \u201cPretty Little Liars\u201d<\/strong><\/p>\n<figure id=\"attachment_21115\" aria-describedby=\"caption-attachment-21115\" style=\"width: 580px\" class=\"wp-caption aligncenter\"><img  loading=\"lazy\"  decoding=\"async\"  class=\" wp-image-21115 pk-lazyload\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  alt=\"Image Via The Indian Express\"  width=\"580\"  height=\"755\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 580px) 100vw, 580px\"  data-pk-src=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042542\/shay-mitchell-750x977.jpg\"  data-pk-srcset=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042542\/shay-mitchell-750x977.jpg 750w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042542\/shay-mitchell-230x300.jpg 230w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042542\/shay-mitchell-786x1024.jpg 786w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042542\/shay-mitchell-768x1000.jpg 768w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042542\/shay-mitchell-380x495.jpg 380w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042542\/shay-mitchell-800x1042.jpg 800w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042542\/shay-mitchell-80x104.jpg 80w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042542\/shay-mitchell-61x80.jpg 61w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042542\/shay-mitchell-620x808.jpg 620w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042542\/shay-mitchell.jpg 820w\" ><figcaption id=\"caption-attachment-21115\" class=\"wp-caption-text\">Image Via The Indian Express<\/figcaption><\/figure>\n<p><strong>Natalie Dormer<\/strong><\/p>\n<figure id=\"attachment_21116\" aria-describedby=\"caption-attachment-21116\" style=\"width: 583px\" class=\"wp-caption aligncenter\"><img  loading=\"lazy\"  decoding=\"async\"  class=\" wp-image-21116 pk-lazyload\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  alt=\"Image Via The Indian Express\"  width=\"583\"  height=\"842\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 583px) 100vw, 583px\"  data-pk-src=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042548\/nataliedormerreuters-709x1024.jpg\"  data-pk-srcset=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042548\/nataliedormerreuters-709x1024.jpg 709w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042548\/nataliedormerreuters-208x300.jpg 208w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042548\/nataliedormerreuters-768x1110.jpg 768w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042548\/nataliedormerreuters-380x549.jpg 380w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042548\/nataliedormerreuters-800x1156.jpg 800w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042548\/nataliedormerreuters-80x116.jpg 80w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042548\/nataliedormerreuters-55x80.jpg 55w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042548\/nataliedormerreuters-620x896.jpg 620w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042548\/nataliedormerreuters.jpg 820w\" ><figcaption id=\"caption-attachment-21116\" class=\"wp-caption-text\">Image Via The Indian Express<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"The 2016 People\u2019s Choice Awards showcased some of the best legs, low-cut necklines and eye-catching gowns of any&hellip;\n","protected":false},"author":19,"featured_media":21108,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[72],"tags":[11966,11965,8566,11964,11963,10597,11967],"class_list":{"0":"post-21105","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-news","8":"tag-2016-peoples-choice-awards","9":"tag-2016-red-carpet","10":"tag-featured","11":"tag-people","12":"tag-peoples-choice-awards","13":"tag-red-carpet","14":"tag-red-carpet-2016","15":"cs-entry","16":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Most Glamorous People&#039;s Choice Awards Red Carpet Looks<\/title>\n<meta name=\"description\" content=\"The 2016 People&#039;s Choice Awards showcased some of the best legs, low-cut necklines and eye-catching gowns of any red carpets. \u00a0Featured below are the best\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/most-glamorous-peoples-choice-awards-red-carpet-looks\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Most Glamorous People&#039;s Choice Awards Red Carpet Looks\" \/>\n<meta property=\"og:description\" content=\"The 2016 People&#039;s Choice Awards showcased some of the best legs, low-cut necklines and eye-catching gowns of any red carpets. \u00a0Featured below are the best\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/most-glamorous-peoples-choice-awards-red-carpet-looks\/\" \/>\n<meta property=\"og:site_name\" content=\"Valley Girl\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-07T19:35:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-01-07T19:35:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042520\/julianne-hough-peoples-choice-awards.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Caitie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/news\\\/most-glamorous-peoples-choice-awards-red-carpet-looks\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/news\\\/most-glamorous-peoples-choice-awards-red-carpet-looks\\\/\"},\"author\":{\"name\":\"Caitie\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#\\\/schema\\\/person\\\/f70ec7ba678580ef6df60d59cf794871\"},\"headline\":\"Most Glamorous People&#8217;s Choice Awards Red Carpet Looks\",\"datePublished\":\"2016-01-07T19:35:14+00:00\",\"dateModified\":\"2016-01-07T19:35:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/news\\\/most-glamorous-peoples-choice-awards-red-carpet-looks\\\/\"},\"wordCount\":214,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/news\\\/most-glamorous-peoples-choice-awards-red-carpet-looks\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/25042520\\\/julianne-hough-peoples-choice-awards.jpg\",\"keywords\":[\"2016 people's choice awards\",\"2016 red carpet\",\"featured\",\"people\",\"people's choice awards\",\"red carpet\",\"red carpet 2016\"],\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/news\\\/most-glamorous-peoples-choice-awards-red-carpet-looks\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/news\\\/most-glamorous-peoples-choice-awards-red-carpet-looks\\\/\",\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/news\\\/most-glamorous-peoples-choice-awards-red-carpet-looks\\\/\",\"name\":\"Most Glamorous People's Choice Awards Red Carpet Looks\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/news\\\/most-glamorous-peoples-choice-awards-red-carpet-looks\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/news\\\/most-glamorous-peoples-choice-awards-red-carpet-looks\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/25042520\\\/julianne-hough-peoples-choice-awards.jpg\",\"datePublished\":\"2016-01-07T19:35:14+00:00\",\"dateModified\":\"2016-01-07T19:35:32+00:00\",\"description\":\"The 2016 People's Choice Awards showcased some of the best legs, low-cut necklines and eye-catching gowns of any red carpets. \u00a0Featured below are the best\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/news\\\/most-glamorous-peoples-choice-awards-red-carpet-looks\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/news\\\/most-glamorous-peoples-choice-awards-red-carpet-looks\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/news\\\/most-glamorous-peoples-choice-awards-red-carpet-looks\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/25042520\\\/julianne-hough-peoples-choice-awards.jpg\",\"contentUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/25042520\\\/julianne-hough-peoples-choice-awards.jpg\",\"width\":1200,\"height\":800,\"caption\":\"Image via In Touch Weekly\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/news\\\/most-glamorous-peoples-choice-awards-red-carpet-looks\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Most Glamorous People&#8217;s Choice Awards Red Carpet Looks\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#website\",\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/\",\"name\":\"Valley Girl\",\"description\":\"A blog for Phoenix area women\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#organization\",\"name\":\"AZFoothills.com LLC\",\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/25072512\\\/apple-touch-icon.jpg\",\"contentUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/25072512\\\/apple-touch-icon.jpg\",\"width\":180,\"height\":180,\"caption\":\"AZFoothills.com LLC\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#\\\/schema\\\/person\\\/f70ec7ba678580ef6df60d59cf794871\",\"name\":\"Caitie\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01977f29c813ff3684a09aaa2c62964f23e2d8ea10be55b0900c7f9356c28d3d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01977f29c813ff3684a09aaa2c62964f23e2d8ea10be55b0900c7f9356c28d3d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01977f29c813ff3684a09aaa2c62964f23e2d8ea10be55b0900c7f9356c28d3d?s=96&d=mm&r=g\",\"caption\":\"Caitie\"},\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/author\\\/caitie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Most Glamorous People's Choice Awards Red Carpet Looks","description":"The 2016 People's Choice Awards showcased some of the best legs, low-cut necklines and eye-catching gowns of any red carpets. \u00a0Featured below are the best","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/most-glamorous-peoples-choice-awards-red-carpet-looks\/","og_locale":"en_US","og_type":"article","og_title":"Most Glamorous People's Choice Awards Red Carpet Looks","og_description":"The 2016 People's Choice Awards showcased some of the best legs, low-cut necklines and eye-catching gowns of any red carpets. \u00a0Featured below are the best","og_url":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/most-glamorous-peoples-choice-awards-red-carpet-looks\/","og_site_name":"Valley Girl","article_published_time":"2016-01-07T19:35:14+00:00","article_modified_time":"2016-01-07T19:35:32+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042520\/julianne-hough-peoples-choice-awards.jpg","type":"image\/jpeg"}],"author":"Caitie","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/most-glamorous-peoples-choice-awards-red-carpet-looks\/#article","isPartOf":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/most-glamorous-peoples-choice-awards-red-carpet-looks\/"},"author":{"name":"Caitie","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#\/schema\/person\/f70ec7ba678580ef6df60d59cf794871"},"headline":"Most Glamorous People&#8217;s Choice Awards Red Carpet Looks","datePublished":"2016-01-07T19:35:14+00:00","dateModified":"2016-01-07T19:35:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/most-glamorous-peoples-choice-awards-red-carpet-looks\/"},"wordCount":214,"commentCount":0,"publisher":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#organization"},"image":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/most-glamorous-peoples-choice-awards-red-carpet-looks\/#primaryimage"},"thumbnailUrl":"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042520\/julianne-hough-peoples-choice-awards.jpg","keywords":["2016 people's choice awards","2016 red carpet","featured","people","people's choice awards","red carpet","red carpet 2016"],"articleSection":["News"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/most-glamorous-peoples-choice-awards-red-carpet-looks\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/most-glamorous-peoples-choice-awards-red-carpet-looks\/","url":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/most-glamorous-peoples-choice-awards-red-carpet-looks\/","name":"Most Glamorous People's Choice Awards Red Carpet Looks","isPartOf":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/most-glamorous-peoples-choice-awards-red-carpet-looks\/#primaryimage"},"image":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/most-glamorous-peoples-choice-awards-red-carpet-looks\/#primaryimage"},"thumbnailUrl":"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042520\/julianne-hough-peoples-choice-awards.jpg","datePublished":"2016-01-07T19:35:14+00:00","dateModified":"2016-01-07T19:35:32+00:00","description":"The 2016 People's Choice Awards showcased some of the best legs, low-cut necklines and eye-catching gowns of any red carpets. \u00a0Featured below are the best","breadcrumb":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/most-glamorous-peoples-choice-awards-red-carpet-looks\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/most-glamorous-peoples-choice-awards-red-carpet-looks\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/most-glamorous-peoples-choice-awards-red-carpet-looks\/#primaryimage","url":"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042520\/julianne-hough-peoples-choice-awards.jpg","contentUrl":"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2016\/01\/25042520\/julianne-hough-peoples-choice-awards.jpg","width":1200,"height":800,"caption":"Image via In Touch Weekly"},{"@type":"BreadcrumbList","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/most-glamorous-peoples-choice-awards-red-carpet-looks\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/"},{"@type":"ListItem","position":2,"name":"Most Glamorous People&#8217;s Choice Awards Red Carpet Looks"}]},{"@type":"WebSite","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#website","url":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/","name":"Valley Girl","description":"A blog for Phoenix area women","publisher":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#organization","name":"AZFoothills.com LLC","url":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#\/schema\/logo\/image\/","url":"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2021\/06\/25072512\/apple-touch-icon.jpg","contentUrl":"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2021\/06\/25072512\/apple-touch-icon.jpg","width":180,"height":180,"caption":"AZFoothills.com LLC"},"image":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#\/schema\/person\/f70ec7ba678580ef6df60d59cf794871","name":"Caitie","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/01977f29c813ff3684a09aaa2c62964f23e2d8ea10be55b0900c7f9356c28d3d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/01977f29c813ff3684a09aaa2c62964f23e2d8ea10be55b0900c7f9356c28d3d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/01977f29c813ff3684a09aaa2c62964f23e2d8ea10be55b0900c7f9356c28d3d?s=96&d=mm&r=g","caption":"Caitie"},"url":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/author\/caitie\/"}]}},"_links":{"self":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/posts\/21105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/comments?post=21105"}],"version-history":[{"count":3,"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/posts\/21105\/revisions"}],"predecessor-version":[{"id":21118,"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/posts\/21105\/revisions\/21118"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/media\/21108"}],"wp:attachment":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/media?parent=21105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/categories?post=21105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/tags?post=21105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}