{"id":19105,"date":"2015-02-23T15:04:45","date_gmt":"2015-02-23T22:04:45","guid":{"rendered":"http:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/?p=19105"},"modified":"2015-02-23T18:18:57","modified_gmt":"2015-02-24T01:18:57","slug":"worst-dressed-women-at-the-2015-academy-awards","status":"publish","type":"post","link":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/worst-dressed-women-at-the-2015-academy-awards\/","title":{"rendered":"Worst-Dressed Women at the 2015 Academy Awards"},"content":{"rendered":"<p><a href=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030822\/79ba31560fabfb89.jpg\"><img  loading=\"lazy\"  decoding=\"async\"  class=\"  wp-image-19081 aligncenter pk-lazyload\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  alt=\"-79ba31560fabfb89\"  width=\"596\"  height=\"397\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 596px) 100vw, 596px\"  data-pk-src=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030822\/79ba31560fabfb89-750x500.jpg\"  data-pk-srcset=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030822\/79ba31560fabfb89-750x500.jpg 750w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030822\/79ba31560fabfb89-300x200.jpg 300w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030822\/79ba31560fabfb89-768x512.jpg 768w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030822\/79ba31560fabfb89-380x253.jpg 380w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030822\/79ba31560fabfb89-800x533.jpg 800w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030822\/79ba31560fabfb89-80x53.jpg 80w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030822\/79ba31560fabfb89-620x413.jpg 620w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030822\/79ba31560fabfb89-850x567.jpg 850w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030822\/79ba31560fabfb89.jpg 960w\" ><\/a><\/p>\n<p>While many celebrities looked smoking hot at the 2015 Academy Awards, as always, there were a few who fell short of expectations. \u00a0Respected and loved as these celebrities are, their gowns were not among the favorites for this year\u2019s ceremony.<\/p>\n<p>Featured below are our picks of the celebrities who really missed the mark. \u00a0These celebrities are talented and admired, yet their gowns have been highly criticized among many fashion blogs and websites as not quite \u201cOscar Glamorous.\u201d Check out the gowns\u00a0below to see if you agree with our verdict.<\/p>\n<p><strong>Marion Cotillard\u00a0<\/strong><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030945\/enhanced-12311-1424649037-2.jpg\"><img  loading=\"lazy\"  decoding=\"async\"  class=\"alignnone size-large wp-image-19109 pk-lqip pk-lazyload\"  src=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030945\/enhanced-12311-1424649037-2-46x80.jpg\"  alt=\"enhanced-12311-1424649037-2\"  width=\"593\"  height=\"1024\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 593px) 100vw, 593px\"  data-pk-src=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030945\/enhanced-12311-1424649037-2-593x1024.jpg\"  data-pk-srcset=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030945\/enhanced-12311-1424649037-2-593x1024.jpg 593w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030945\/enhanced-12311-1424649037-2-174x300.jpg 174w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030945\/enhanced-12311-1424649037-2-380x656.jpg 380w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030945\/enhanced-12311-1424649037-2-80x138.jpg 80w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030945\/enhanced-12311-1424649037-2-46x80.jpg 46w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030945\/enhanced-12311-1424649037-2-620x1070.jpg 620w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030945\/enhanced-12311-1424649037-2.jpg 625w\" ><\/a><\/p>\n<p style=\"text-align: left;\"><strong>Chlo\u00eb Grace Moretz<\/strong><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030948\/enhanced-5526-1424652070-2.jpg\"><img  loading=\"lazy\"  decoding=\"async\"  class=\"alignnone  wp-image-19110 pk-lazyload\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  alt=\"enhanced-5526-1424652070-2\"  width=\"603\"  height=\"907\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 603px) 100vw, 603px\"  data-pk-src=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030948\/enhanced-5526-1424652070-2.jpg\"  data-pk-srcset=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030948\/enhanced-5526-1424652070-2.jpg 625w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030948\/enhanced-5526-1424652070-2-199x300.jpg 199w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030948\/enhanced-5526-1424652070-2-380x572.jpg 380w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030948\/enhanced-5526-1424652070-2-80x120.jpg 80w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030948\/enhanced-5526-1424652070-2-53x80.jpg 53w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030948\/enhanced-5526-1424652070-2-620x932.jpg 620w\" ><\/a><\/p>\n<p style=\"text-align: left;\"><strong>Ava DuVernay<\/strong><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030951\/enhanced-29654-1424652332-26.jpg\"><img  loading=\"lazy\"  decoding=\"async\"  class=\"alignnone size-full wp-image-19111 pk-lqip pk-lazyload\"  src=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030951\/enhanced-29654-1424652332-26-80x120.jpg\"  alt=\"enhanced-29654-1424652332-26\"  width=\"625\"  height=\"941\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 625px) 100vw, 625px\"  data-pk-src=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030951\/enhanced-29654-1424652332-26.jpg\"  data-pk-srcset=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030951\/enhanced-29654-1424652332-26.jpg 625w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030951\/enhanced-29654-1424652332-26-199x300.jpg 199w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030951\/enhanced-29654-1424652332-26-380x572.jpg 380w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030951\/enhanced-29654-1424652332-26-80x120.jpg 80w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030951\/enhanced-29654-1424652332-26-53x80.jpg 53w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030951\/enhanced-29654-1424652332-26-620x933.jpg 620w\" ><\/a><\/p>\n<p><strong>Nicole Kidman<\/strong><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030955\/enhanced-669-1424652945-3.jpg\"><img  loading=\"lazy\"  decoding=\"async\"  class=\"alignnone size-full wp-image-19112 pk-lqip pk-lazyload\"  src=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030955\/enhanced-669-1424652945-3-80x120.jpg\"  alt=\"enhanced-669-1424652945-3\"  width=\"625\"  height=\"941\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 625px) 100vw, 625px\"  data-pk-src=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030955\/enhanced-669-1424652945-3.jpg\"  data-pk-srcset=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030955\/enhanced-669-1424652945-3.jpg 625w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030955\/enhanced-669-1424652945-3-199x300.jpg 199w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030955\/enhanced-669-1424652945-3-380x572.jpg 380w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030955\/enhanced-669-1424652945-3-80x120.jpg 80w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030955\/enhanced-669-1424652945-3-53x80.jpg 53w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030955\/enhanced-669-1424652945-3-620x933.jpg 620w\" ><\/a><\/p>\n<p style=\"text-align: left;\"><strong>Solange Knowles<\/strong><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030958\/enhanced-30688-1424653083-15.jpg\"><img  loading=\"lazy\"  decoding=\"async\"  class=\"alignnone size-full wp-image-19113 pk-lqip pk-lazyload\"  src=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030958\/enhanced-30688-1424653083-15-80x120.jpg\"  alt=\"enhanced-30688-1424653083-15\"  width=\"625\"  height=\"941\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 625px) 100vw, 625px\"  data-pk-src=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030958\/enhanced-30688-1424653083-15.jpg\"  data-pk-srcset=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030958\/enhanced-30688-1424653083-15.jpg 625w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030958\/enhanced-30688-1424653083-15-199x300.jpg 199w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030958\/enhanced-30688-1424653083-15-380x572.jpg 380w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030958\/enhanced-30688-1424653083-15-80x120.jpg 80w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030958\/enhanced-30688-1424653083-15-53x80.jpg 53w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030958\/enhanced-30688-1424653083-15-620x933.jpg 620w\" ><\/a><\/p>\n<p style=\"text-align: left;\"><strong>Scarlett Johansson<\/strong><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25031001\/enhanced-29017-1424653573-10.jpg\"><img  loading=\"lazy\"  decoding=\"async\"  class=\"alignnone size-large wp-image-19114 pk-lqip pk-lazyload\"  src=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25031001\/enhanced-29017-1424653573-10-42x80.jpg\"  alt=\"enhanced-29017-1424653573-10\"  width=\"533\"  height=\"1024\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 533px) 100vw, 533px\"  data-pk-src=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25031001\/enhanced-29017-1424653573-10-533x1024.jpg\"  data-pk-srcset=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25031001\/enhanced-29017-1424653573-10-533x1024.jpg 533w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25031001\/enhanced-29017-1424653573-10-156x300.jpg 156w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25031001\/enhanced-29017-1424653573-10-380x730.jpg 380w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25031001\/enhanced-29017-1424653573-10-80x154.jpg 80w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25031001\/enhanced-29017-1424653573-10-42x80.jpg 42w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25031001\/enhanced-29017-1424653573-10-620x1191.jpg 620w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25031001\/enhanced-29017-1424653573-10.jpg 625w\" ><\/a><\/p>\n<p style=\"text-align: left;\"><strong>Keira Knightley<\/strong><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25031005\/enhanced-14941-1424653667-8.jpg\"><img  loading=\"lazy\"  decoding=\"async\"  class=\"alignnone size-large wp-image-19115 pk-lqip pk-lazyload\"  src=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25031005\/enhanced-14941-1424653667-8-46x80.jpg\"  alt=\"enhanced-14941-1424653667-8\"  width=\"584\"  height=\"1024\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 584px) 100vw, 584px\"  data-pk-src=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25031005\/enhanced-14941-1424653667-8-584x1024.jpg\"  data-pk-srcset=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25031005\/enhanced-14941-1424653667-8-584x1024.jpg 584w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25031005\/enhanced-14941-1424653667-8-171x300.jpg 171w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25031005\/enhanced-14941-1424653667-8-380x666.jpg 380w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25031005\/enhanced-14941-1424653667-8-80x140.jpg 80w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25031005\/enhanced-14941-1424653667-8-46x80.jpg 46w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25031005\/enhanced-14941-1424653667-8-620x1086.jpg 620w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25031005\/enhanced-14941-1424653667-8.jpg 625w\" ><\/a><\/p>\n<p style=\"text-align: left;\"><strong>Lady Gaga<\/strong><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25031010\/enhanced-31939-1424653792-45.jpg\"><img  loading=\"lazy\"  decoding=\"async\"  class=\"alignnone size-full wp-image-19116 pk-lqip pk-lazyload\"  src=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25031010\/enhanced-31939-1424653792-45-80x120.jpg\"  alt=\"enhanced-31939-1424653792-45\"  width=\"625\"  height=\"940\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 625px) 100vw, 625px\"  data-pk-src=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25031010\/enhanced-31939-1424653792-45.jpg\"  data-pk-srcset=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25031010\/enhanced-31939-1424653792-45.jpg 625w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25031010\/enhanced-31939-1424653792-45-199x300.jpg 199w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25031010\/enhanced-31939-1424653792-45-380x572.jpg 380w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25031010\/enhanced-31939-1424653792-45-80x120.jpg 80w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25031010\/enhanced-31939-1424653792-45-53x80.jpg 53w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25031010\/enhanced-31939-1424653792-45-620x932.jpg 620w\" ><\/a><\/p>\n<p style=\"text-align: center;\">To view our picks of the most glamorous gowns at the 2015 Oscars, click <a href=\"http:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/most-glamorous-gowns-at-the-2015-oscars\/\">HERE<\/a>.<\/p>\n<p style=\"text-align: center;\"><em>Images courtesy of Getty Images\/ Photographer: Jason Merritt and Frazer Harrison<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"While many celebrities looked smoking hot at the 2015 Academy Awards, as always, there were a few who&hellip;\n","protected":false},"author":19,"featured_media":19108,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[72],"tags":[8869,8282,8566,11279,8868,8461,11278,11277],"class_list":{"0":"post-19105","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-news","8":"tag-academy-awards","9":"tag-fashion","10":"tag-featured","11":"tag-gowns","12":"tag-oscars","13":"tag-style","14":"tag-worst-dressed-academy-awards","15":"tag-worst-dressed-oscars","16":"cs-entry","17":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Worst-Dressed Women at the 2015 Academy Awards<\/title>\n<meta name=\"description\" content=\"While many celebrities looked smoking hot at the 2015 Academy Awards, as always, there were a few who fell short of expectations. \u00a0Respected and loved as\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/worst-dressed-women-at-the-2015-academy-awards\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Worst-Dressed Women at the 2015 Academy Awards\" \/>\n<meta property=\"og:description\" content=\"While many celebrities looked smoking hot at the 2015 Academy Awards, as always, there were a few who fell short of expectations. \u00a0Respected and loved as\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/worst-dressed-women-at-the-2015-academy-awards\/\" \/>\n<meta property=\"og:site_name\" content=\"Valley Girl\" \/>\n<meta property=\"article:published_time\" content=\"2015-02-23T22:04:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-02-24T01:18:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030941\/marion-cotillard-oscars-2015-worst-dressed.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"506\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Caitie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/news\\\/worst-dressed-women-at-the-2015-academy-awards\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/news\\\/worst-dressed-women-at-the-2015-academy-awards\\\/\"},\"author\":{\"name\":\"Caitie\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#\\\/schema\\\/person\\\/f70ec7ba678580ef6df60d59cf794871\"},\"headline\":\"Worst-Dressed Women at the 2015 Academy Awards\",\"datePublished\":\"2015-02-23T22:04:45+00:00\",\"dateModified\":\"2015-02-24T01:18:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/news\\\/worst-dressed-women-at-the-2015-academy-awards\\\/\"},\"wordCount\":138,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/news\\\/worst-dressed-women-at-the-2015-academy-awards\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/25030941\\\/marion-cotillard-oscars-2015-worst-dressed.jpg\",\"keywords\":[\"Academy Awards\",\"fashion\",\"featured\",\"gowns\",\"Oscars\",\"style\",\"worst dressed academy awards\",\"worst dressed oscars\"],\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/news\\\/worst-dressed-women-at-the-2015-academy-awards\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/news\\\/worst-dressed-women-at-the-2015-academy-awards\\\/\",\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/news\\\/worst-dressed-women-at-the-2015-academy-awards\\\/\",\"name\":\"Worst-Dressed Women at the 2015 Academy Awards\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/news\\\/worst-dressed-women-at-the-2015-academy-awards\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/news\\\/worst-dressed-women-at-the-2015-academy-awards\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/25030941\\\/marion-cotillard-oscars-2015-worst-dressed.jpg\",\"datePublished\":\"2015-02-23T22:04:45+00:00\",\"dateModified\":\"2015-02-24T01:18:57+00:00\",\"description\":\"While many celebrities looked smoking hot at the 2015 Academy Awards, as always, there were a few who fell short of expectations. \u00a0Respected and loved as\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/news\\\/worst-dressed-women-at-the-2015-academy-awards\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/news\\\/worst-dressed-women-at-the-2015-academy-awards\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/news\\\/worst-dressed-women-at-the-2015-academy-awards\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/25030941\\\/marion-cotillard-oscars-2015-worst-dressed.jpg\",\"contentUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/25030941\\\/marion-cotillard-oscars-2015-worst-dressed.jpg\",\"width\":900,\"height\":506},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/news\\\/worst-dressed-women-at-the-2015-academy-awards\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Worst-Dressed Women at the 2015 Academy Awards\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#website\",\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/\",\"name\":\"Valley Girl\",\"description\":\"A blog for Phoenix area women\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#organization\",\"name\":\"AZFoothills.com LLC\",\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/25072512\\\/apple-touch-icon.jpg\",\"contentUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/25072512\\\/apple-touch-icon.jpg\",\"width\":180,\"height\":180,\"caption\":\"AZFoothills.com LLC\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#\\\/schema\\\/person\\\/f70ec7ba678580ef6df60d59cf794871\",\"name\":\"Caitie\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01977f29c813ff3684a09aaa2c62964f23e2d8ea10be55b0900c7f9356c28d3d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01977f29c813ff3684a09aaa2c62964f23e2d8ea10be55b0900c7f9356c28d3d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01977f29c813ff3684a09aaa2c62964f23e2d8ea10be55b0900c7f9356c28d3d?s=96&d=mm&r=g\",\"caption\":\"Caitie\"},\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/author\\\/caitie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Worst-Dressed Women at the 2015 Academy Awards","description":"While many celebrities looked smoking hot at the 2015 Academy Awards, as always, there were a few who fell short of expectations. \u00a0Respected and loved as","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/worst-dressed-women-at-the-2015-academy-awards\/","og_locale":"en_US","og_type":"article","og_title":"Worst-Dressed Women at the 2015 Academy Awards","og_description":"While many celebrities looked smoking hot at the 2015 Academy Awards, as always, there were a few who fell short of expectations. \u00a0Respected and loved as","og_url":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/worst-dressed-women-at-the-2015-academy-awards\/","og_site_name":"Valley Girl","article_published_time":"2015-02-23T22:04:45+00:00","article_modified_time":"2015-02-24T01:18:57+00:00","og_image":[{"width":900,"height":506,"url":"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030941\/marion-cotillard-oscars-2015-worst-dressed.jpg","type":"image\/jpeg"}],"author":"Caitie","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/worst-dressed-women-at-the-2015-academy-awards\/#article","isPartOf":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/worst-dressed-women-at-the-2015-academy-awards\/"},"author":{"name":"Caitie","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#\/schema\/person\/f70ec7ba678580ef6df60d59cf794871"},"headline":"Worst-Dressed Women at the 2015 Academy Awards","datePublished":"2015-02-23T22:04:45+00:00","dateModified":"2015-02-24T01:18:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/worst-dressed-women-at-the-2015-academy-awards\/"},"wordCount":138,"commentCount":0,"publisher":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#organization"},"image":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/worst-dressed-women-at-the-2015-academy-awards\/#primaryimage"},"thumbnailUrl":"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030941\/marion-cotillard-oscars-2015-worst-dressed.jpg","keywords":["Academy Awards","fashion","featured","gowns","Oscars","style","worst dressed academy awards","worst dressed oscars"],"articleSection":["News"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/worst-dressed-women-at-the-2015-academy-awards\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/worst-dressed-women-at-the-2015-academy-awards\/","url":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/worst-dressed-women-at-the-2015-academy-awards\/","name":"Worst-Dressed Women at the 2015 Academy Awards","isPartOf":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/worst-dressed-women-at-the-2015-academy-awards\/#primaryimage"},"image":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/worst-dressed-women-at-the-2015-academy-awards\/#primaryimage"},"thumbnailUrl":"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030941\/marion-cotillard-oscars-2015-worst-dressed.jpg","datePublished":"2015-02-23T22:04:45+00:00","dateModified":"2015-02-24T01:18:57+00:00","description":"While many celebrities looked smoking hot at the 2015 Academy Awards, as always, there were a few who fell short of expectations. \u00a0Respected and loved as","breadcrumb":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/worst-dressed-women-at-the-2015-academy-awards\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/worst-dressed-women-at-the-2015-academy-awards\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/worst-dressed-women-at-the-2015-academy-awards\/#primaryimage","url":"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030941\/marion-cotillard-oscars-2015-worst-dressed.jpg","contentUrl":"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2015\/02\/25030941\/marion-cotillard-oscars-2015-worst-dressed.jpg","width":900,"height":506},{"@type":"BreadcrumbList","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/worst-dressed-women-at-the-2015-academy-awards\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/"},{"@type":"ListItem","position":2,"name":"Worst-Dressed Women at the 2015 Academy Awards"}]},{"@type":"WebSite","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#website","url":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/","name":"Valley Girl","description":"A blog for Phoenix area women","publisher":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#organization","name":"AZFoothills.com LLC","url":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#\/schema\/logo\/image\/","url":"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2021\/06\/25072512\/apple-touch-icon.jpg","contentUrl":"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2021\/06\/25072512\/apple-touch-icon.jpg","width":180,"height":180,"caption":"AZFoothills.com LLC"},"image":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#\/schema\/person\/f70ec7ba678580ef6df60d59cf794871","name":"Caitie","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/01977f29c813ff3684a09aaa2c62964f23e2d8ea10be55b0900c7f9356c28d3d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/01977f29c813ff3684a09aaa2c62964f23e2d8ea10be55b0900c7f9356c28d3d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/01977f29c813ff3684a09aaa2c62964f23e2d8ea10be55b0900c7f9356c28d3d?s=96&d=mm&r=g","caption":"Caitie"},"url":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/author\/caitie\/"}]}},"_links":{"self":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/posts\/19105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/comments?post=19105"}],"version-history":[{"count":6,"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/posts\/19105\/revisions"}],"predecessor-version":[{"id":19127,"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/posts\/19105\/revisions\/19127"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/media\/19108"}],"wp:attachment":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/media?parent=19105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/categories?post=19105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/tags?post=19105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}