{"id":17648,"date":"2014-07-15T10:27:30","date_gmt":"2014-07-15T17:27:30","guid":{"rendered":"http:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/?p=17648"},"modified":"2014-07-16T10:29:23","modified_gmt":"2014-07-16T17:29:23","slug":"taylor-swift-shares-unique-insight-wallstreet-journal-op-ed","status":"publish","type":"post","link":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/taylor-swift-shares-unique-insight-wallstreet-journal-op-ed\/","title":{"rendered":"Taylor Swift Shares Unique Insight in Wallstreet Journal Op-Ed"},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2014\/07\/25022353\/taylor-swift-winning-650-430.jpg\"><img  loading=\"lazy\"  decoding=\"async\"  class=\"alignnone size-full wp-image-17697 pk-lqip pk-lazyload\"  src=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2014\/07\/25022353\/taylor-swift-winning-650-430-80x53.jpg\"  alt=\"taylor-swift-winning-650-430\"  width=\"650\"  height=\"430\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 650px) 100vw, 650px\"  data-pk-src=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2014\/07\/25022353\/taylor-swift-winning-650-430.jpg\"  data-pk-srcset=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2014\/07\/25022353\/taylor-swift-winning-650-430.jpg 650w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2014\/07\/25022353\/taylor-swift-winning-650-430-300x198.jpg 300w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2014\/07\/25022353\/taylor-swift-winning-650-430-380x251.jpg 380w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2014\/07\/25022353\/taylor-swift-winning-650-430-80x53.jpg 80w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2014\/07\/25022353\/taylor-swift-winning-650-430-620x410.jpg 620w\" ><\/a><br \/>\n<em>Image Courtesy of Billboard.com<\/em><\/p>\n<p>Even if you love to hate Taylor Swift, some of her business tips she gave in her op-ed in the Wallstreet Journal provide unique insights that are worth looking into. \u00a0These insights share her experience with the music industry and social media.<\/p>\n<p>Featured below are five of the insights that an optimistic person in the music industry such as Taylor decided to share in he op-ed.<\/p>\n<p><strong>1. Bye, bye autographs?<\/strong><\/p>\n<p><span style=\"color: #000000;\">\u201cI haven\u2019t been asked for an autograph since the invention of the iPhone with a front-facing camera. The only memento \u201ckids these days\u201d want is a selfie.\u201d<\/span><span style=\"color: #000000;\"><br \/>\n<\/span><\/p>\n<p><strong>2. Social Media is Key<\/strong><\/p>\n<p><span style=\"color: #000000;\">\u201cA friend of mine, who is an actress, told me that when the casting for her recent movie came down to two actresses, the casting director chose the actress with more Twitter followers.\u201d<\/span><span style=\"color: #000000;\"><br \/>\n<\/span><\/p>\n<p><strong>3. Fans First, Records Later.<\/strong><\/p>\n<p><span style=\"color: #000000;\">\u201cIn the future, artists will get record deals because they have fans\u2014not the other way around<\/span><em style=\"color: #000000;\">.\u201d<\/em><\/p>\n<p><strong>4. Overlapping Genres<\/strong><\/p>\n<p><span style=\"color: #000000;\">\u201cAnother theme I see fading into the gray is genre distinction. These days, nothing great you hear on the radio seems to come from just one musical influence.\u201d<\/span><span style=\"color: #000000;\"><br \/>\n<\/span><\/p>\n<p><strong>5. Fans are Key<\/strong><\/p>\n<p><span style=\"color: #000000;\">\u201cI think forming a bond with fans in the future will come in the form of constantly providing them with the element of surprise. No, I did not say \u201cshock\u201d; I said \u201csurprise.\u201d I believe couples can stay in love for decades if they just continue to surprise each other, so why can\u2019t this love affair exist between an artist and their fans?\u201d<\/span><\/p>\n<p>To read the whole op-ed, click <a href=\"http:\/\/online.wsj.com\/articles\/for-taylor-swift-the-future-of-music-is-a-love-story-1404763219\">HERE<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"Image Courtesy of Billboard.com Even if you love to hate Taylor Swift, some of her business tips she&hellip;\n","protected":false},"author":19,"featured_media":17697,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[555,72],"tags":[8566,3871,10789,10787,10786,10785,10788,10784],"class_list":{"0":"post-17648","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-art-music","8":"category-news","9":"tag-featured","10":"tag-taylor-swift","11":"tag-taylor-swift-autograph","12":"tag-taylor-swift-business","13":"tag-taylor-swift-business-insight","14":"tag-taylor-swift-op-ed","15":"tag-taylor-swift-social-media","16":"tag-taylor-swift-wallstreet-journal","17":"cs-entry","18":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Taylor Swift Shares Unique Insight in Wallstreet Journal Op-Ed<\/title>\n<meta name=\"description\" content=\"Image Courtesy of Billboard.com Even if you love to hate Taylor Swift, some of her business tips she gave in her op-ed in the Wallstreet Journal provide\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/taylor-swift-shares-unique-insight-wallstreet-journal-op-ed\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Taylor Swift Shares Unique Insight in Wallstreet Journal Op-Ed\" \/>\n<meta property=\"og:description\" content=\"Image Courtesy of Billboard.com Even if you love to hate Taylor Swift, some of her business tips she gave in her op-ed in the Wallstreet Journal provide\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/taylor-swift-shares-unique-insight-wallstreet-journal-op-ed\/\" \/>\n<meta property=\"og:site_name\" content=\"Valley Girl\" \/>\n<meta property=\"article:published_time\" content=\"2014-07-15T17:27:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-07-16T17:29:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2014\/07\/25022353\/taylor-swift-winning-650-430.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"430\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Caitie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/news\\\/taylor-swift-shares-unique-insight-wallstreet-journal-op-ed\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/news\\\/taylor-swift-shares-unique-insight-wallstreet-journal-op-ed\\\/\"},\"author\":{\"name\":\"Caitie\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#\\\/schema\\\/person\\\/f70ec7ba678580ef6df60d59cf794871\"},\"headline\":\"Taylor Swift Shares Unique Insight in Wallstreet Journal Op-Ed\",\"datePublished\":\"2014-07-15T17:27:30+00:00\",\"dateModified\":\"2014-07-16T17:29:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/news\\\/taylor-swift-shares-unique-insight-wallstreet-journal-op-ed\\\/\"},\"wordCount\":273,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/news\\\/taylor-swift-shares-unique-insight-wallstreet-journal-op-ed\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/wp-content\\\/uploads\\\/2014\\\/07\\\/25022353\\\/taylor-swift-winning-650-430.jpg\",\"keywords\":[\"featured\",\"Taylor Swift\",\"taylor swift autograph\",\"taylor swift business\",\"taylor swift business insight\",\"taylor swift op-ed\",\"taylor swift social media\",\"taylor swift wallstreet journal\"],\"articleSection\":[\"Art &amp; Music\",\"News\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/news\\\/taylor-swift-shares-unique-insight-wallstreet-journal-op-ed\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/news\\\/taylor-swift-shares-unique-insight-wallstreet-journal-op-ed\\\/\",\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/news\\\/taylor-swift-shares-unique-insight-wallstreet-journal-op-ed\\\/\",\"name\":\"Taylor Swift Shares Unique Insight in Wallstreet Journal Op-Ed\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/news\\\/taylor-swift-shares-unique-insight-wallstreet-journal-op-ed\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/news\\\/taylor-swift-shares-unique-insight-wallstreet-journal-op-ed\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/wp-content\\\/uploads\\\/2014\\\/07\\\/25022353\\\/taylor-swift-winning-650-430.jpg\",\"datePublished\":\"2014-07-15T17:27:30+00:00\",\"dateModified\":\"2014-07-16T17:29:23+00:00\",\"description\":\"Image Courtesy of Billboard.com Even if you love to hate Taylor Swift, some of her business tips she gave in her op-ed in the Wallstreet Journal provide\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/news\\\/taylor-swift-shares-unique-insight-wallstreet-journal-op-ed\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/news\\\/taylor-swift-shares-unique-insight-wallstreet-journal-op-ed\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/news\\\/taylor-swift-shares-unique-insight-wallstreet-journal-op-ed\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/wp-content\\\/uploads\\\/2014\\\/07\\\/25022353\\\/taylor-swift-winning-650-430.jpg\",\"contentUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/wp-content\\\/uploads\\\/2014\\\/07\\\/25022353\\\/taylor-swift-winning-650-430.jpg\",\"width\":650,\"height\":430},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/news\\\/taylor-swift-shares-unique-insight-wallstreet-journal-op-ed\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Taylor Swift Shares Unique Insight in Wallstreet Journal Op-Ed\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#website\",\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/\",\"name\":\"Valley Girl\",\"description\":\"A blog for Phoenix area women\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#organization\",\"name\":\"AZFoothills.com LLC\",\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/25072512\\\/apple-touch-icon.jpg\",\"contentUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/25072512\\\/apple-touch-icon.jpg\",\"width\":180,\"height\":180,\"caption\":\"AZFoothills.com LLC\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#\\\/schema\\\/person\\\/f70ec7ba678580ef6df60d59cf794871\",\"name\":\"Caitie\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01977f29c813ff3684a09aaa2c62964f23e2d8ea10be55b0900c7f9356c28d3d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01977f29c813ff3684a09aaa2c62964f23e2d8ea10be55b0900c7f9356c28d3d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01977f29c813ff3684a09aaa2c62964f23e2d8ea10be55b0900c7f9356c28d3d?s=96&d=mm&r=g\",\"caption\":\"Caitie\"},\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/author\\\/caitie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Taylor Swift Shares Unique Insight in Wallstreet Journal Op-Ed","description":"Image Courtesy of Billboard.com Even if you love to hate Taylor Swift, some of her business tips she gave in her op-ed in the Wallstreet Journal provide","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/taylor-swift-shares-unique-insight-wallstreet-journal-op-ed\/","og_locale":"en_US","og_type":"article","og_title":"Taylor Swift Shares Unique Insight in Wallstreet Journal Op-Ed","og_description":"Image Courtesy of Billboard.com Even if you love to hate Taylor Swift, some of her business tips she gave in her op-ed in the Wallstreet Journal provide","og_url":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/taylor-swift-shares-unique-insight-wallstreet-journal-op-ed\/","og_site_name":"Valley Girl","article_published_time":"2014-07-15T17:27:30+00:00","article_modified_time":"2014-07-16T17:29:23+00:00","og_image":[{"width":650,"height":430,"url":"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2014\/07\/25022353\/taylor-swift-winning-650-430.jpg","type":"image\/jpeg"}],"author":"Caitie","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/taylor-swift-shares-unique-insight-wallstreet-journal-op-ed\/#article","isPartOf":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/taylor-swift-shares-unique-insight-wallstreet-journal-op-ed\/"},"author":{"name":"Caitie","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#\/schema\/person\/f70ec7ba678580ef6df60d59cf794871"},"headline":"Taylor Swift Shares Unique Insight in Wallstreet Journal Op-Ed","datePublished":"2014-07-15T17:27:30+00:00","dateModified":"2014-07-16T17:29:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/taylor-swift-shares-unique-insight-wallstreet-journal-op-ed\/"},"wordCount":273,"commentCount":0,"publisher":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#organization"},"image":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/taylor-swift-shares-unique-insight-wallstreet-journal-op-ed\/#primaryimage"},"thumbnailUrl":"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2014\/07\/25022353\/taylor-swift-winning-650-430.jpg","keywords":["featured","Taylor Swift","taylor swift autograph","taylor swift business","taylor swift business insight","taylor swift op-ed","taylor swift social media","taylor swift wallstreet journal"],"articleSection":["Art &amp; Music","News"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/taylor-swift-shares-unique-insight-wallstreet-journal-op-ed\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/taylor-swift-shares-unique-insight-wallstreet-journal-op-ed\/","url":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/taylor-swift-shares-unique-insight-wallstreet-journal-op-ed\/","name":"Taylor Swift Shares Unique Insight in Wallstreet Journal Op-Ed","isPartOf":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/taylor-swift-shares-unique-insight-wallstreet-journal-op-ed\/#primaryimage"},"image":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/taylor-swift-shares-unique-insight-wallstreet-journal-op-ed\/#primaryimage"},"thumbnailUrl":"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2014\/07\/25022353\/taylor-swift-winning-650-430.jpg","datePublished":"2014-07-15T17:27:30+00:00","dateModified":"2014-07-16T17:29:23+00:00","description":"Image Courtesy of Billboard.com Even if you love to hate Taylor Swift, some of her business tips she gave in her op-ed in the Wallstreet Journal provide","breadcrumb":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/taylor-swift-shares-unique-insight-wallstreet-journal-op-ed\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/taylor-swift-shares-unique-insight-wallstreet-journal-op-ed\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/taylor-swift-shares-unique-insight-wallstreet-journal-op-ed\/#primaryimage","url":"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2014\/07\/25022353\/taylor-swift-winning-650-430.jpg","contentUrl":"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2014\/07\/25022353\/taylor-swift-winning-650-430.jpg","width":650,"height":430},{"@type":"BreadcrumbList","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/news\/taylor-swift-shares-unique-insight-wallstreet-journal-op-ed\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/"},{"@type":"ListItem","position":2,"name":"Taylor Swift Shares Unique Insight in Wallstreet Journal Op-Ed"}]},{"@type":"WebSite","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#website","url":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/","name":"Valley Girl","description":"A blog for Phoenix area women","publisher":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#organization","name":"AZFoothills.com LLC","url":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#\/schema\/logo\/image\/","url":"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2021\/06\/25072512\/apple-touch-icon.jpg","contentUrl":"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2021\/06\/25072512\/apple-touch-icon.jpg","width":180,"height":180,"caption":"AZFoothills.com LLC"},"image":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#\/schema\/person\/f70ec7ba678580ef6df60d59cf794871","name":"Caitie","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/01977f29c813ff3684a09aaa2c62964f23e2d8ea10be55b0900c7f9356c28d3d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/01977f29c813ff3684a09aaa2c62964f23e2d8ea10be55b0900c7f9356c28d3d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/01977f29c813ff3684a09aaa2c62964f23e2d8ea10be55b0900c7f9356c28d3d?s=96&d=mm&r=g","caption":"Caitie"},"url":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/author\/caitie\/"}]}},"_links":{"self":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/posts\/17648","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/comments?post=17648"}],"version-history":[{"count":4,"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/posts\/17648\/revisions"}],"predecessor-version":[{"id":17700,"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/posts\/17648\/revisions\/17700"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/media\/17697"}],"wp:attachment":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/media?parent=17648"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/categories?post=17648"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/tags?post=17648"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}