{"id":11922,"date":"2012-06-20T10:18:08","date_gmt":"2012-06-20T17:18:08","guid":{"rendered":"http:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/?p=11922"},"modified":"2012-06-20T22:31:08","modified_gmt":"2012-06-21T05:31:08","slug":"best-summer-travel-tech-gadgets","status":"publish","type":"post","link":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/travel\/best-summer-travel-tech-gadgets\/","title":{"rendered":"Best Summer Travel Tech Gadgets"},"content":{"rendered":"<p>Wherever your summer travels may take you, these state-of-the-art tech gadgets will preserve the fun long after it\u2019s over:<\/p>\n<p><strong>Garmin N\u00fcvi 3590LMT<br \/>\n<a href=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2012\/06\/25001648\/garmin-nuvi.jpg\"><img  loading=\"lazy\"  decoding=\"async\"  class=\"aligncenter size-full wp-image-11923 pk-lqip pk-lazyload\"  title=\"garmin nuvi\"  src=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2012\/06\/25001648\/garmin-nuvi-80x57.jpg\"  alt=\"\"  width=\"400\"  height=\"286\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 400px) 100vw, 400px\"  data-pk-src=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2012\/06\/25001648\/garmin-nuvi.jpg\"  data-pk-srcset=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2012\/06\/25001648\/garmin-nuvi.jpg 400w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2012\/06\/25001648\/garmin-nuvi-300x215.jpg 300w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2012\/06\/25001648\/garmin-nuvi-380x272.jpg 380w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2012\/06\/25001648\/garmin-nuvi-80x58.jpg 80w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2012\/06\/25001648\/garmin-nuvi-100x72.jpg 100w\" ><\/a>\u00a0<\/strong><\/p>\n<p>With a free lifetime digital 3-D traffic and map updates, the N\u00fcvi 3590LMT will get you to your destination in the fastest and most efficient way possible. The user friendly touch screen is easy to use, but why have your automated directions in hand when you can just as easily direct it from the sound of your voice? Speak and the device will listen and direct. All you have to do is drive. \u00a0<a href=\"https:\/\/buy.garmin.com\/shop\/shop.do?pID=96637\"><em>garmin.com<\/em><\/a><\/p>\n<p><strong>Earhero Ear Buds<br \/>\n<a href=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2012\/06\/25001650\/earhero.jpg\"><img  loading=\"lazy\"  decoding=\"async\"  class=\"aligncenter size-full wp-image-11924 pk-lqip pk-lazyload\"  title=\"earhero\"  src=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2012\/06\/25001650\/earhero-80x57.jpg\"  alt=\"\"  width=\"400\"  height=\"286\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 400px) 100vw, 400px\"  data-pk-src=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2012\/06\/25001650\/earhero.jpg\"  data-pk-srcset=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2012\/06\/25001650\/earhero.jpg 400w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2012\/06\/25001650\/earhero-300x215.jpg 300w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2012\/06\/25001650\/earhero-380x272.jpg 380w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2012\/06\/25001650\/earhero-80x58.jpg 80w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2012\/06\/25001650\/earhero-100x72.jpg 100w\" ><\/a>\u00a0<\/strong><\/p>\n<p>Have you ever wanted to listen to your headphones, but still have enough sound room to hear what\u2019s going on around you? With Earhero Ear Buds you can. Sold only recently to government security agencies, these little buds are just small enough to not fill the entire ear canal, which gives you leeway to listen to music at that just-right volume while remaining aware of your external surroundings. <em><a href=\"http:\/\/www.earhero.com\/\" target=\"_blank\">earhero.com<\/a><\/em><\/p>\n<p><strong>Jawbone Waterproof Speaker<br \/>\n<a href=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2012\/06\/25001700\/hbz-JAMBOX-by-Jawbone-red-in-hand-sixhundred-poolside-tech-0611-de.jpg\"><img  loading=\"lazy\"  decoding=\"async\"  class=\"aligncenter size-full wp-image-11932 pk-lqip pk-lazyload\"  title=\"hbz-JAMBOX-by-Jawbone-red-in-hand-sixhundred-poolside-tech-0611-de\"  src=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2012\/06\/25001700\/hbz-JAMBOX-by-Jawbone-red-in-hand-sixhundred-poolside-tech-0611-de-80x102.jpg\"  alt=\"\"  width=\"360\"  height=\"460\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 360px) 100vw, 360px\"  data-pk-src=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2012\/06\/25001700\/hbz-JAMBOX-by-Jawbone-red-in-hand-sixhundred-poolside-tech-0611-de.jpg\"  data-pk-srcset=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2012\/06\/25001700\/hbz-JAMBOX-by-Jawbone-red-in-hand-sixhundred-poolside-tech-0611-de.jpg 360w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2012\/06\/25001700\/hbz-JAMBOX-by-Jawbone-red-in-hand-sixhundred-poolside-tech-0611-de-235x300.jpg 235w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2012\/06\/25001700\/hbz-JAMBOX-by-Jawbone-red-in-hand-sixhundred-poolside-tech-0611-de-80x102.jpg 80w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2012\/06\/25001700\/hbz-JAMBOX-by-Jawbone-red-in-hand-sixhundred-poolside-tech-0611-de-63x80.jpg 63w\" ><\/a><\/strong><\/p>\n<p>You can literally take this thing anywhere \u2013 beach, park, hotel, pool, and yes, even the office. Completely wireless, the Jambox turns any phone, tablet or mobile device into a portable, hi-fi sound system where you can enjoy clear and crisp music, movies, games and chats with others thanks to precision-tuned drivers and dual passive bass radiators. <em><a href=\"http:\/\/www.jawbone.com\" target=\"_blank\">jawbone.com<\/a><\/em><\/p>\n<p><strong>HTC One X Smartphone<br \/>\n<a href=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2012\/06\/25001653\/HTC-smartphone.jpg\"><img  loading=\"lazy\"  decoding=\"async\"  class=\"aligncenter size-full wp-image-11925 pk-lqip pk-lazyload\"  title=\"HTC smartphone\"  src=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2012\/06\/25001653\/HTC-smartphone-80x57.jpg\"  alt=\"\"  width=\"400\"  height=\"286\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 400px) 100vw, 400px\"  data-pk-src=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2012\/06\/25001653\/HTC-smartphone.jpg\"  data-pk-srcset=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2012\/06\/25001653\/HTC-smartphone.jpg 400w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2012\/06\/25001653\/HTC-smartphone-300x215.jpg 300w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2012\/06\/25001653\/HTC-smartphone-380x272.jpg 380w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2012\/06\/25001653\/HTC-smartphone-80x58.jpg 80w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2012\/06\/25001653\/HTC-smartphone-100x72.jpg 100w\" ><\/a>\u00a0<\/strong><\/p>\n<p>This isn\u2019t just your average smartphone. Equipped with a camera that\u2019s capable of snapping up to four shots per second, you\u2019ll be ready to savor any unexpected moment that happens on your summer getaway. Even better, the aperture settings up to F 2.0, enabling low light, artistic shots. <em><a href=\"http:\/\/www.wireless.att.com\/cell-phone-service\/cell-phone-details\/?device=HTC+One+%28TM%29+X+-+Gray&q_sku=sku5980289#fbid=bib0GVhiN_L\">att.com<\/a><\/em><\/p>\n<p><strong>GoPro Her02<br \/>\n<a href=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2012\/06\/25001655\/gopro.jpg\"><img  loading=\"lazy\"  decoding=\"async\"  class=\"aligncenter size-full wp-image-11926 pk-lqip pk-lazyload\"  title=\"gopro\"  src=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2012\/06\/25001655\/gopro-80x112.jpg\"  alt=\"\"  width=\"400\"  height=\"558\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 400px) 100vw, 400px\"  data-pk-src=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2012\/06\/25001655\/gopro.jpg\"  data-pk-srcset=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2012\/06\/25001655\/gopro.jpg 400w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2012\/06\/25001655\/gopro-215x300.jpg 215w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2012\/06\/25001655\/gopro-380x530.jpg 380w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2012\/06\/25001655\/gopro-80x112.jpg 80w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2012\/06\/25001655\/gopro-57x80.jpg 57w\" ><\/a>\u00a0<\/strong><\/p>\n<p>This wearable video camera shoots 1080p hi-definition video and 11-megapixel stills at up to 200 feet. Strap on the GoPro to your helmet, chest, car, or from wherever you\u2019d like to film, to capture first-person video with the touch of a button. And not to worry, it\u2019s completely waterproof. Note: The strap is an additional GoPro accessory.\u00a0<a href=\"http:\/\/www.gopro.com\/\"><em>gopro.com<\/em><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"Wherever your summer travels may take you, these state-of-the-art tech gadgets will preserve the fun long after it&#8217;s over.\n","protected":false},"author":15,"featured_media":11932,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1728],"tags":[8989,9148,9137,9147,8320,8358],"class_list":{"0":"post-11922","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-travel","8":"tag-summer","9":"tag-summer-tech-gadgets","10":"tag-tech","11":"tag-tech-gadgets","12":"tag-technology","13":"tag-travel-2","14":"cs-entry","15":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Best Summer Travel Tech Gadgets<\/title>\n<meta name=\"description\" content=\"Wherever your summer travels may take you, these state-of-the-art tech gadgets will preserve the fun long after it&#039;s over.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/travel\/best-summer-travel-tech-gadgets\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Best Summer Travel Tech Gadgets\" \/>\n<meta property=\"og:description\" content=\"Wherever your summer travels may take you, these state-of-the-art tech gadgets will preserve the fun long after it&#039;s over.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/travel\/best-summer-travel-tech-gadgets\/\" \/>\n<meta property=\"og:site_name\" content=\"Valley Girl\" \/>\n<meta property=\"article:published_time\" content=\"2012-06-20T17:18:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-06-21T05:31:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2012\/06\/25001700\/hbz-JAMBOX-by-Jawbone-red-in-hand-sixhundred-poolside-tech-0611-de.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"360\" \/>\n\t<meta property=\"og:image:height\" content=\"460\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christina Silvestri\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/travel\\\/best-summer-travel-tech-gadgets\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/travel\\\/best-summer-travel-tech-gadgets\\\/\"},\"author\":{\"name\":\"Christina Silvestri\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#\\\/schema\\\/person\\\/102a14a82f84a3a7eb4fba676cdc798c\"},\"headline\":\"Best Summer Travel Tech Gadgets\",\"datePublished\":\"2012-06-20T17:18:08+00:00\",\"dateModified\":\"2012-06-21T05:31:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/travel\\\/best-summer-travel-tech-gadgets\\\/\"},\"wordCount\":358,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/travel\\\/best-summer-travel-tech-gadgets\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/wp-content\\\/uploads\\\/2012\\\/06\\\/25001700\\\/hbz-JAMBOX-by-Jawbone-red-in-hand-sixhundred-poolside-tech-0611-de.jpg\",\"keywords\":[\"summer\",\"summer tech gadgets\",\"tech\",\"tech gadgets\",\"technology\",\"travel\"],\"articleSection\":[\"Travel\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/travel\\\/best-summer-travel-tech-gadgets\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/travel\\\/best-summer-travel-tech-gadgets\\\/\",\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/travel\\\/best-summer-travel-tech-gadgets\\\/\",\"name\":\"Best Summer Travel Tech Gadgets\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/travel\\\/best-summer-travel-tech-gadgets\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/travel\\\/best-summer-travel-tech-gadgets\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/wp-content\\\/uploads\\\/2012\\\/06\\\/25001700\\\/hbz-JAMBOX-by-Jawbone-red-in-hand-sixhundred-poolside-tech-0611-de.jpg\",\"datePublished\":\"2012-06-20T17:18:08+00:00\",\"dateModified\":\"2012-06-21T05:31:08+00:00\",\"description\":\"Wherever your summer travels may take you, these state-of-the-art tech gadgets will preserve the fun long after it's over.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/travel\\\/best-summer-travel-tech-gadgets\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/travel\\\/best-summer-travel-tech-gadgets\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/travel\\\/best-summer-travel-tech-gadgets\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/wp-content\\\/uploads\\\/2012\\\/06\\\/25001700\\\/hbz-JAMBOX-by-Jawbone-red-in-hand-sixhundred-poolside-tech-0611-de.jpg\",\"contentUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/wp-content\\\/uploads\\\/2012\\\/06\\\/25001700\\\/hbz-JAMBOX-by-Jawbone-red-in-hand-sixhundred-poolside-tech-0611-de.jpg\",\"width\":360,\"height\":460},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/travel\\\/best-summer-travel-tech-gadgets\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Best Summer Travel Tech Gadgets\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#website\",\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/\",\"name\":\"Valley Girl\",\"description\":\"A blog for Phoenix area women\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#organization\",\"name\":\"AZFoothills.com LLC\",\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/25072512\\\/apple-touch-icon.jpg\",\"contentUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/25072512\\\/apple-touch-icon.jpg\",\"width\":180,\"height\":180,\"caption\":\"AZFoothills.com LLC\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#\\\/schema\\\/person\\\/102a14a82f84a3a7eb4fba676cdc798c\",\"name\":\"Christina Silvestri\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e2669e014914c205b1a61b9d6b10b01bf7590c89812e24dc4171858568d08486?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e2669e014914c205b1a61b9d6b10b01bf7590c89812e24dc4171858568d08486?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e2669e014914c205b1a61b9d6b10b01bf7590c89812e24dc4171858568d08486?s=96&d=mm&r=g\",\"caption\":\"Christina Silvestri\"},\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/author\\\/christina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Best Summer Travel Tech Gadgets","description":"Wherever your summer travels may take you, these state-of-the-art tech gadgets will preserve the fun long after it's over.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/travel\/best-summer-travel-tech-gadgets\/","og_locale":"en_US","og_type":"article","og_title":"Best Summer Travel Tech Gadgets","og_description":"Wherever your summer travels may take you, these state-of-the-art tech gadgets will preserve the fun long after it's over.","og_url":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/travel\/best-summer-travel-tech-gadgets\/","og_site_name":"Valley Girl","article_published_time":"2012-06-20T17:18:08+00:00","article_modified_time":"2012-06-21T05:31:08+00:00","og_image":[{"width":360,"height":460,"url":"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2012\/06\/25001700\/hbz-JAMBOX-by-Jawbone-red-in-hand-sixhundred-poolside-tech-0611-de.jpg","type":"image\/jpeg"}],"author":"Christina Silvestri","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/travel\/best-summer-travel-tech-gadgets\/#article","isPartOf":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/travel\/best-summer-travel-tech-gadgets\/"},"author":{"name":"Christina Silvestri","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#\/schema\/person\/102a14a82f84a3a7eb4fba676cdc798c"},"headline":"Best Summer Travel Tech Gadgets","datePublished":"2012-06-20T17:18:08+00:00","dateModified":"2012-06-21T05:31:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/travel\/best-summer-travel-tech-gadgets\/"},"wordCount":358,"commentCount":0,"publisher":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#organization"},"image":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/travel\/best-summer-travel-tech-gadgets\/#primaryimage"},"thumbnailUrl":"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2012\/06\/25001700\/hbz-JAMBOX-by-Jawbone-red-in-hand-sixhundred-poolside-tech-0611-de.jpg","keywords":["summer","summer tech gadgets","tech","tech gadgets","technology","travel"],"articleSection":["Travel"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/travel\/best-summer-travel-tech-gadgets\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/travel\/best-summer-travel-tech-gadgets\/","url":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/travel\/best-summer-travel-tech-gadgets\/","name":"Best Summer Travel Tech Gadgets","isPartOf":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/travel\/best-summer-travel-tech-gadgets\/#primaryimage"},"image":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/travel\/best-summer-travel-tech-gadgets\/#primaryimage"},"thumbnailUrl":"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2012\/06\/25001700\/hbz-JAMBOX-by-Jawbone-red-in-hand-sixhundred-poolside-tech-0611-de.jpg","datePublished":"2012-06-20T17:18:08+00:00","dateModified":"2012-06-21T05:31:08+00:00","description":"Wherever your summer travels may take you, these state-of-the-art tech gadgets will preserve the fun long after it's over.","breadcrumb":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/travel\/best-summer-travel-tech-gadgets\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/travel\/best-summer-travel-tech-gadgets\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/travel\/best-summer-travel-tech-gadgets\/#primaryimage","url":"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2012\/06\/25001700\/hbz-JAMBOX-by-Jawbone-red-in-hand-sixhundred-poolside-tech-0611-de.jpg","contentUrl":"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2012\/06\/25001700\/hbz-JAMBOX-by-Jawbone-red-in-hand-sixhundred-poolside-tech-0611-de.jpg","width":360,"height":460},{"@type":"BreadcrumbList","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/travel\/best-summer-travel-tech-gadgets\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/"},{"@type":"ListItem","position":2,"name":"Best Summer Travel Tech Gadgets"}]},{"@type":"WebSite","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#website","url":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/","name":"Valley Girl","description":"A blog for Phoenix area women","publisher":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#organization","name":"AZFoothills.com LLC","url":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#\/schema\/logo\/image\/","url":"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2021\/06\/25072512\/apple-touch-icon.jpg","contentUrl":"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2021\/06\/25072512\/apple-touch-icon.jpg","width":180,"height":180,"caption":"AZFoothills.com LLC"},"image":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#\/schema\/person\/102a14a82f84a3a7eb4fba676cdc798c","name":"Christina Silvestri","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/e2669e014914c205b1a61b9d6b10b01bf7590c89812e24dc4171858568d08486?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e2669e014914c205b1a61b9d6b10b01bf7590c89812e24dc4171858568d08486?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e2669e014914c205b1a61b9d6b10b01bf7590c89812e24dc4171858568d08486?s=96&d=mm&r=g","caption":"Christina Silvestri"},"url":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/author\/christina\/"}]}},"_links":{"self":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/posts\/11922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/comments?post=11922"}],"version-history":[{"count":7,"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/posts\/11922\/revisions"}],"predecessor-version":[{"id":11935,"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/posts\/11922\/revisions\/11935"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/media\/11932"}],"wp:attachment":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/media?parent=11922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/categories?post=11922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/tags?post=11922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}