{"id":1105,"date":"2009-02-10T10:27:26","date_gmt":"2009-02-10T17:27:26","guid":{"rendered":"http:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/?p=1105"},"modified":"2009-03-03T12:44:48","modified_gmt":"2009-03-03T19:44:48","slug":"skin-authority-at-sanctuary","status":"publish","type":"post","link":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/shopping\/skin-authority-at-sanctuary\/","title":{"rendered":"Skin Authority at Sanctuary"},"content":{"rendered":"<p><!--StartFragment--><\/p>\n<p class=\"MsoNormal\">As if <strong>Sanctuary on Camelback Mountain Resort & Spa<\/strong> wasn\u2019t already one of our favorite luxe locales in the area, now their updated selection of products and treatments has made visiting this gorgeous spa even more tempting. The resort is now the only location in Scottsdale to carry leading skin care line <strong>Skin Authority\u2019s products<\/strong> and offer their treatments. As a part of the line\u2019s launch at Sanctuary, I recently received a Skin Authority facial\u2014and I have to admit, this is one \u201cindulgence\u201d that has now become a necessity in my life.<\/p>\n<p class=\"MsoNormal\">\u00a0<img  loading=\"lazy\"  decoding=\"async\"  class=\"aligncenter size-full wp-image-1106 pk-lqip pk-lazyload\"  title=\"spaexteriornight\"  src=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2009\/02\/24215209\/spaexteriornight-80x43.jpg\"  alt=\"spaexteriornight\"  width=\"600\"  height=\"325\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 600px) 100vw, 600px\"  data-pk-src=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2009\/02\/24215209\/spaexteriornight.jpg\"  data-pk-srcset=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2009\/02\/24215209\/spaexteriornight.jpg 600w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2009\/02\/24215209\/spaexteriornight-300x162.jpg 300w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2009\/02\/24215209\/spaexteriornight-380x206.jpg 380w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2009\/02\/24215209\/spaexteriornight-80x42.jpg 80w\" ><\/p>\n<p class=\"MsoNormal\">Before you write these products off as just more tubes of goop to clutter your bathroom counter, listen up. Skin Authority, founded by Celeste Hilling, is a premier skin care lifestyle brand, offering 25 home care products and 19 professional products. The company truly believes that each person deserves their own unique skin care plan, as everyone is different. In one customized treatment, new pathways into the skin tissue are developed, enabling the deepest parts of your skin tissue to be nourished and create new cell production.<\/p>\n<p class=\"MsoNormal\"><strong>The Skin Authority Lifestyle Program<\/strong> is customized to fit your skin care needs and make healthy changes\u2014it includes a professional skin analysis, facial and body treatments, home care products and kits and an at-home skin care \u201ccoach\u201d to assist you with your program. Treatments include Transformation for the Face, Body and Soul Rituals and Transformation for the Hands and Feet. No matter what you\u2019re focus area is, all of the offerings use Skin Authority signature products, including high-concentration ingredients at the lowest penetrating pH. Another perk is that all things Skin Authority are paraben, dye and added fragrance-free, and many are packaged in biodegradable materials, helping to contribute to a sustainable lifestyle.<\/p>\n<p class=\"MsoNormal\"><img  loading=\"lazy\"  decoding=\"async\"  class=\"aligncenter size-full wp-image-1107 pk-lqip pk-lazyload\"  title=\"sanctuarysignaturephoto\"  src=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2009\/02\/24215212\/sanctuarysignaturephoto-80x43.jpg\"  alt=\"sanctuarysignaturephoto\"  width=\"600\"  height=\"325\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 600px) 100vw, 600px\"  data-pk-src=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2009\/02\/24215212\/sanctuarysignaturephoto.jpg\"  data-pk-srcset=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2009\/02\/24215212\/sanctuarysignaturephoto.jpg 600w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2009\/02\/24215212\/sanctuarysignaturephoto-300x162.jpg 300w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2009\/02\/24215212\/sanctuarysignaturephoto-380x206.jpg 380w, https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2009\/02\/24215212\/sanctuarysignaturephoto-80x42.jpg 80w\" ><\/p>\n<p class=\"MsoNormal\">If it\u2019s new and effective products you\u2019re after, the Skin Authority Web site is able to suggest an item or kit to meet your particular needs. This is helpful, as the amount of products available can be a bit overwhelming at first. (Although the Bright Eyes Kit, Deep Detox Ritual Mask and Hand Foot Body Restoration all sound like they would work wonders.) <span>\u00a0<\/span><\/p>\n<p class=\"MsoNormal\">The best part of the face treatment I received? It only lasted a mere 20 minutes, and I walked out with noticeably smoother, healthier skin that simply glowed. In fact, I even received a couple compliments that evening, making it completely worth it.<\/p>\n<p class=\"MsoNormal\">To learn more, visit <a href=\"http:\/\/www.skinauthority.com\/\" target=\"_blank\">www.skinauthority.com<\/a>. <em>\u2013Amy Strand, associate editor <\/em><\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p><!--EndFragment--><\/p>\n","protected":false},"excerpt":{"rendered":"As if Sanctuary on Camelback Mountain Resort &#038; Spa wasn\u2019t already one of our favorite luxe locales in&hellip;\n","protected":false},"author":3,"featured_media":1106,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[3],"tags":[329,326,323,324,325,327,328,330],"class_list":{"0":"post-1105","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-shopping","8":"tag-body-and-soul-rituals","9":"tag-celeste-hilling","10":"tag-sanctuary-on-camelback-mountain-resort-spa","11":"tag-skin-authority","12":"tag-skin-authority-facial","13":"tag-the-skin-authority-lifestyle-program","14":"tag-transformation-for-the-face","15":"tag-transformation-for-the-hands-and-feet","16":"cs-entry","17":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Skin Authority at Sanctuary<\/title>\n<meta name=\"description\" content=\"The resort is now the only location in Scottsdale to carry leading skin care line Skin Authority\u2019s products and offer their treatments.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/shopping\/skin-authority-at-sanctuary\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Skin Authority at Sanctuary\" \/>\n<meta property=\"og:description\" content=\"The resort is now the only location in Scottsdale to carry leading skin care line Skin Authority\u2019s products and offer their treatments.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/shopping\/skin-authority-at-sanctuary\/\" \/>\n<meta property=\"og:site_name\" content=\"Valley Girl\" \/>\n<meta property=\"article:published_time\" content=\"2009-02-10T17:27:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2009-03-03T19:44:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2009\/02\/24215209\/spaexteriornight.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"325\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Amy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/shopping\\\/skin-authority-at-sanctuary\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/shopping\\\/skin-authority-at-sanctuary\\\/\"},\"author\":{\"name\":\"Amy\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#\\\/schema\\\/person\\\/282ffad7a1348eeb69769301f08cef12\"},\"headline\":\"Skin Authority at Sanctuary\",\"datePublished\":\"2009-02-10T17:27:26+00:00\",\"dateModified\":\"2009-03-03T19:44:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/shopping\\\/skin-authority-at-sanctuary\\\/\"},\"wordCount\":417,\"commentCount\":16,\"publisher\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/shopping\\\/skin-authority-at-sanctuary\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/wp-content\\\/uploads\\\/2009\\\/02\\\/24215209\\\/spaexteriornight.jpg\",\"keywords\":[\"Body and Soul Rituals\",\"Celeste Hilling\",\"Sanctuary on Camelback Mountain Resort &amp; Spa\",\"Skin Authority\",\"Skin Authority facial\",\"The Skin Authority Lifestyle Program\",\"Transformation for the Face\",\"Transformation for the Hands and Feet\"],\"articleSection\":[\"Shopping &amp; Beauty\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/shopping\\\/skin-authority-at-sanctuary\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/shopping\\\/skin-authority-at-sanctuary\\\/\",\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/shopping\\\/skin-authority-at-sanctuary\\\/\",\"name\":\"Skin Authority at Sanctuary\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/shopping\\\/skin-authority-at-sanctuary\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/shopping\\\/skin-authority-at-sanctuary\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/wp-content\\\/uploads\\\/2009\\\/02\\\/24215209\\\/spaexteriornight.jpg\",\"datePublished\":\"2009-02-10T17:27:26+00:00\",\"dateModified\":\"2009-03-03T19:44:48+00:00\",\"description\":\"The resort is now the only location in Scottsdale to carry leading skin care line Skin Authority\u2019s products and offer their treatments.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/shopping\\\/skin-authority-at-sanctuary\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/shopping\\\/skin-authority-at-sanctuary\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/shopping\\\/skin-authority-at-sanctuary\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/wp-content\\\/uploads\\\/2009\\\/02\\\/24215209\\\/spaexteriornight.jpg\",\"contentUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/wp-content\\\/uploads\\\/2009\\\/02\\\/24215209\\\/spaexteriornight.jpg\",\"width\":600,\"height\":325},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/shopping\\\/skin-authority-at-sanctuary\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Skin Authority at Sanctuary\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#website\",\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/\",\"name\":\"Valley Girl\",\"description\":\"A blog for Phoenix area women\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#organization\",\"name\":\"AZFoothills.com LLC\",\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/25072512\\\/apple-touch-icon.jpg\",\"contentUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/25072512\\\/apple-touch-icon.jpg\",\"width\":180,\"height\":180,\"caption\":\"AZFoothills.com LLC\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/#\\\/schema\\\/person\\\/282ffad7a1348eeb69769301f08cef12\",\"name\":\"Amy\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4feb77afed70533d2e7c42633078ff911f17edd1eb7ee2a1eae5fe7f0a569af3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4feb77afed70533d2e7c42633078ff911f17edd1eb7ee2a1eae5fe7f0a569af3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4feb77afed70533d2e7c42633078ff911f17edd1eb7ee2a1eae5fe7f0a569af3?s=96&d=mm&r=g\",\"caption\":\"Amy\"},\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/valleygirlblog\\\/author\\\/amy\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Skin Authority at Sanctuary","description":"The resort is now the only location in Scottsdale to carry leading skin care line Skin Authority\u2019s products and offer their treatments.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/shopping\/skin-authority-at-sanctuary\/","og_locale":"en_US","og_type":"article","og_title":"Skin Authority at Sanctuary","og_description":"The resort is now the only location in Scottsdale to carry leading skin care line Skin Authority\u2019s products and offer their treatments.","og_url":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/shopping\/skin-authority-at-sanctuary\/","og_site_name":"Valley Girl","article_published_time":"2009-02-10T17:27:26+00:00","article_modified_time":"2009-03-03T19:44:48+00:00","og_image":[{"width":600,"height":325,"url":"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2009\/02\/24215209\/spaexteriornight.jpg","type":"image\/jpeg"}],"author":"Amy","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/shopping\/skin-authority-at-sanctuary\/#article","isPartOf":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/shopping\/skin-authority-at-sanctuary\/"},"author":{"name":"Amy","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#\/schema\/person\/282ffad7a1348eeb69769301f08cef12"},"headline":"Skin Authority at Sanctuary","datePublished":"2009-02-10T17:27:26+00:00","dateModified":"2009-03-03T19:44:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/shopping\/skin-authority-at-sanctuary\/"},"wordCount":417,"commentCount":16,"publisher":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#organization"},"image":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/shopping\/skin-authority-at-sanctuary\/#primaryimage"},"thumbnailUrl":"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2009\/02\/24215209\/spaexteriornight.jpg","keywords":["Body and Soul Rituals","Celeste Hilling","Sanctuary on Camelback Mountain Resort &amp; Spa","Skin Authority","Skin Authority facial","The Skin Authority Lifestyle Program","Transformation for the Face","Transformation for the Hands and Feet"],"articleSection":["Shopping &amp; Beauty"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/shopping\/skin-authority-at-sanctuary\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/shopping\/skin-authority-at-sanctuary\/","url":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/shopping\/skin-authority-at-sanctuary\/","name":"Skin Authority at Sanctuary","isPartOf":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/shopping\/skin-authority-at-sanctuary\/#primaryimage"},"image":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/shopping\/skin-authority-at-sanctuary\/#primaryimage"},"thumbnailUrl":"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2009\/02\/24215209\/spaexteriornight.jpg","datePublished":"2009-02-10T17:27:26+00:00","dateModified":"2009-03-03T19:44:48+00:00","description":"The resort is now the only location in Scottsdale to carry leading skin care line Skin Authority\u2019s products and offer their treatments.","breadcrumb":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/shopping\/skin-authority-at-sanctuary\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/shopping\/skin-authority-at-sanctuary\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/shopping\/skin-authority-at-sanctuary\/#primaryimage","url":"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2009\/02\/24215209\/spaexteriornight.jpg","contentUrl":"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2009\/02\/24215209\/spaexteriornight.jpg","width":600,"height":325},{"@type":"BreadcrumbList","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/shopping\/skin-authority-at-sanctuary\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/"},{"@type":"ListItem","position":2,"name":"Skin Authority at Sanctuary"}]},{"@type":"WebSite","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#website","url":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/","name":"Valley Girl","description":"A blog for Phoenix area women","publisher":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#organization","name":"AZFoothills.com LLC","url":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#\/schema\/logo\/image\/","url":"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2021\/06\/25072512\/apple-touch-icon.jpg","contentUrl":"https:\/\/media.arizonafoothillsmagazine.com\/valleygirlblog\/wp-content\/uploads\/2021\/06\/25072512\/apple-touch-icon.jpg","width":180,"height":180,"caption":"AZFoothills.com LLC"},"image":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/#\/schema\/person\/282ffad7a1348eeb69769301f08cef12","name":"Amy","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/4feb77afed70533d2e7c42633078ff911f17edd1eb7ee2a1eae5fe7f0a569af3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4feb77afed70533d2e7c42633078ff911f17edd1eb7ee2a1eae5fe7f0a569af3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4feb77afed70533d2e7c42633078ff911f17edd1eb7ee2a1eae5fe7f0a569af3?s=96&d=mm&r=g","caption":"Amy"},"url":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/author\/amy\/"}]}},"_links":{"self":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/posts\/1105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/comments?post=1105"}],"version-history":[{"count":7,"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/posts\/1105\/revisions"}],"predecessor-version":[{"id":1110,"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/posts\/1105\/revisions\/1110"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/media\/1106"}],"wp:attachment":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/media?parent=1105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/categories?post=1105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/valleygirlblog\/wp-json\/wp\/v2\/tags?post=1105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}