{"id":65,"count":1,"description":"","link":"https:\/\/www.arizonafoothillsmagazine.com\/people\/tag\/jana-hadany","name":"Jana Hadany","slug":"jana-hadany","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jana Hadany Archives - Trendsetters<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.arizonafoothillsmagazine.com\/people\/tag\/jana-hadany\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jana Hadany Archives - Trendsetters\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.arizonafoothillsmagazine.com\/people\/tag\/jana-hadany\" \/>\n<meta property=\"og:site_name\" content=\"Trendsetters\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/people\\\/tag\\\/jana-hadany\",\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/people\\\/tag\\\/jana-hadany\",\"name\":\"Jana Hadany Archives - Trendsetters\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/people\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/people\\\/tag\\\/jana-hadany#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/people\\\/tag\\\/jana-hadany#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/people\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jana Hadany\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/people\\\/#website\",\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/people\\\/\",\"name\":\"Trendsetters\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/people\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/people\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/people\\\/#organization\",\"name\":\"AZFoothills.com LLC\",\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/people\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/people\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/people\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/24111316\\\/apple-touch-icon.jpg\",\"contentUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/people\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/24111316\\\/apple-touch-icon.jpg\",\"width\":180,\"height\":180,\"caption\":\"AZFoothills.com LLC\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/people\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jana Hadany Archives - Trendsetters","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.arizonafoothillsmagazine.com\/people\/tag\/jana-hadany","og_locale":"en_US","og_type":"article","og_title":"Jana Hadany Archives - Trendsetters","og_url":"https:\/\/www.arizonafoothillsmagazine.com\/people\/tag\/jana-hadany","og_site_name":"Trendsetters","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.arizonafoothillsmagazine.com\/people\/tag\/jana-hadany","url":"https:\/\/www.arizonafoothillsmagazine.com\/people\/tag\/jana-hadany","name":"Jana Hadany Archives - Trendsetters","isPartOf":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/people\/#website"},"breadcrumb":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/people\/tag\/jana-hadany#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.arizonafoothillsmagazine.com\/people\/tag\/jana-hadany#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.arizonafoothillsmagazine.com\/people\/"},{"@type":"ListItem","position":2,"name":"Jana Hadany"}]},{"@type":"WebSite","@id":"https:\/\/www.arizonafoothillsmagazine.com\/people\/#website","url":"https:\/\/www.arizonafoothillsmagazine.com\/people\/","name":"Trendsetters","description":"","publisher":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/people\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.arizonafoothillsmagazine.com\/people\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.arizonafoothillsmagazine.com\/people\/#organization","name":"AZFoothills.com LLC","url":"https:\/\/www.arizonafoothillsmagazine.com\/people\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.arizonafoothillsmagazine.com\/people\/#\/schema\/logo\/image\/","url":"https:\/\/media.arizonafoothillsmagazine.com\/people\/wp-content\/uploads\/2020\/10\/24111316\/apple-touch-icon.jpg","contentUrl":"https:\/\/media.arizonafoothillsmagazine.com\/people\/wp-content\/uploads\/2020\/10\/24111316\/apple-touch-icon.jpg","width":180,"height":180,"caption":"AZFoothills.com LLC"},"image":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/people\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/people\/wp-json\/wp\/v2\/tags\/65","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/people\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/people\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/people\/wp-json\/wp\/v2\/posts?tags=65"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}