{"id":497,"date":"2012-10-30T09:00:56","date_gmt":"2012-10-30T16:00:56","guid":{"rendered":"http:\/\/www.arizonafoothillsmagazine.com\/people\/?p=497"},"modified":"2012-12-11T08:50:49","modified_gmt":"2012-12-11T15:50:49","slug":"aaron-may-chef-boyaaron","status":"publish","type":"post","link":"https:\/\/www.arizonafoothillsmagazine.com\/people\/chefs\/aaron-may-chef-boyaaron","title":{"rendered":"Aaron May: Chef BoyAARON"},"content":{"rendered":"<p><a href=\"https:\/\/media.arizonafoothillsmagazine.com\/people\/wp-content\/uploads\/2012\/10\/24053749\/Aaron-May-2.jpg\"><img  loading=\"lazy\"  decoding=\"async\"  class=\"aligncenter size-full wp-image-498 pk-lqip pk-lazyload\"  title=\"Aaron May 2\"  src=\"https:\/\/media.arizonafoothillsmagazine.com\/people\/wp-content\/uploads\/2012\/10\/24053749\/Aaron-May-2-80x114.jpg\"  alt=\"\"  width=\"650\"  height=\"927\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 650px) 100vw, 650px\"  data-pk-src=\"https:\/\/media.arizonafoothillsmagazine.com\/people\/wp-content\/uploads\/2012\/10\/24053749\/Aaron-May-2.jpg\"  data-pk-srcset=\"https:\/\/media.arizonafoothillsmagazine.com\/people\/wp-content\/uploads\/2012\/10\/24053749\/Aaron-May-2.jpg 650w, https:\/\/media.arizonafoothillsmagazine.com\/people\/wp-content\/uploads\/2012\/10\/24053749\/Aaron-May-2-210x300.jpg 210w, https:\/\/media.arizonafoothillsmagazine.com\/people\/wp-content\/uploads\/2012\/10\/24053749\/Aaron-May-2-380x542.jpg 380w, https:\/\/media.arizonafoothillsmagazine.com\/people\/wp-content\/uploads\/2012\/10\/24053749\/Aaron-May-2-80x114.jpg 80w, https:\/\/media.arizonafoothillsmagazine.com\/people\/wp-content\/uploads\/2012\/10\/24053749\/Aaron-May-2-56x80.jpg 56w, https:\/\/media.arizonafoothillsmagazine.com\/people\/wp-content\/uploads\/2012\/10\/24053749\/Aaron-May-2-74x106.jpg 74w, https:\/\/media.arizonafoothillsmagazine.com\/people\/wp-content\/uploads\/2012\/10\/24053749\/Aaron-May-2-620x884.jpg 620w\" ><\/a><\/p>\n<p>We began 20 sentences that each person finished in their own words. Here\u2019s what Chef, Aaron May, had to say about cooking, family and peers and everything in between.<\/p>\n<p>Age: 35<br \/>\nTitle: chef<br \/>\nMarried\/Single: single<br \/>\nKids: no thanks<br \/>\nLive: Scottsdale<\/p>\n<h3 id=\"i-was-born\">I was born\u2026<\/h3>\n<p>on Christmas day, downtown<br \/>\nChicago.<\/p>\n<h3 id=\"my-favorite-thing-about-arizona\">My favorite thing about Arizona\u2026<\/h3>\n<p>is the diversity of mountain, desert and city life.<\/p>\n<h3 id=\"im-listening-to\">I&#8217;m listening to\u2026<\/h3>\n<p>Father John Misty, Fear Fun. Album of the Year.<\/p>\n<h3 id=\"my-family\">My family\u2026<\/h3>\n<p>is not afraid to share their opinions.<\/p>\n<h3 id=\"if-i-could-have-dinner-with-anyone-it-would-be\">If I could have dinner with anyone, it would be\u2026<\/h3>\n<p>my late grandfather. He was very influential in my life, and missed out on a lot of great things since he passed away.<\/p>\n<h3 id=\"one-thing-i-cannot-live-without\">One thing I cannot live without\u2026<\/h3>\n<p>a kitchen.<\/p>\n<h3 id=\"when-i-was-younger-i-wanted-to-be\">When I was younger, I wanted to be\u2026<\/h3>\n<p>older.<\/p>\n<h3 id=\"im-inspired-by\">I&#8217;m inspired by\u2026<\/h3>\n<p>my peers. There&#8217;s nothing more motivating than a little friendly competition.<\/p>\n<h3 id=\"the-one-person-who-motivates-me-is\">The one person who motivates me is\u2026<\/h3>\n<p>on my heels, catching up fast.<\/p>\n<h3 id=\"if-could-change-anything-in-the-world-it-would-be\">If could change anything in the world, it would be&#8230;<\/h3>\n<p>people&#8217;s minds.<\/p>\n<h3 id=\"the-perfect-day-would-be\">The perfect day would be\u2026<\/h3>\n<p>cooking with friends, loud music and stiff drinks on a patio somewhere warm.<\/p>\n<h3 id=\"my-first-job-was\">My first job was\u2026<\/h3>\n<p>at a restaurant, of course.<\/p>\n<h3 id=\"my-favorite-escape\">My favorite escape\u2026<\/h3>\n<p>must remain a secret.<\/p>\n<h3 id=\"my-life\">My life\u2026<\/h3>\n<p>is a work in progress.<\/p>\n<h3 id=\"im-currently-working-on\">I&#8217;m currently working on\u2026<\/h3>\n<p>new restaurants, old recipes.<\/p>\n<h3 id=\"always\">Always\u2026<\/h3>\n<p>take a chance.<\/p>\n<h3 id=\"never\">Never&#8230;<\/h3>\n<p>miss an opportunity, its so much more fun to say yes.<\/p>\n<h3 id=\"favorite-quote\">Favorite Quote&#8230;<\/h3>\n<p>&#8220;Women are meant to be loved, not to be understood&#8221; \u2014 Oscar Wilde<\/p>\n<h3 id=\"biggest-dream\">Biggest Dream&#8230;<\/h3>\n<p>I am living it every day.<\/p>\n<p>Check out his latest venture,\u00a0<a href=\"http:\/\/renegadetapandkitchen.com\" target=\"_blank\">renegadetapandkitchen.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"Meet Chef, Aaron May, as he talks about cooking, family and peers and everything in between. \n","protected":false},"author":2,"featured_media":499,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[21],"tags":[11],"class_list":["post-497","post","type-post","status-publish","format-standard","has-post-thumbnail","category-chefs","tag-featured","cs-entry","cs-video-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aaron May: Chef BoyAARON<\/title>\n<meta name=\"description\" content=\"Meet Chef, Aaron May, as he talks about cooking, family and peers and everything in between.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.arizonafoothillsmagazine.com\/people\/chefs\/aaron-may-chef-boyaaron\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aaron May: Chef BoyAARON\" \/>\n<meta property=\"og:description\" content=\"Meet Chef, Aaron May, as he talks about cooking, family and peers and everything in between.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.arizonafoothillsmagazine.com\/people\/chefs\/aaron-may-chef-boyaaron\" \/>\n<meta property=\"og:site_name\" content=\"Trendsetters\" \/>\n<meta property=\"article:published_time\" content=\"2012-10-30T16:00:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-12-11T15:50:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.arizonafoothillsmagazine.com\/people\/wp-content\/uploads\/2012\/10\/24053752\/Aaron-May-21.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"385\" \/>\n\t<meta property=\"og:image:height\" content=\"356\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"kbolton\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"kbolton\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/people\\\/chefs\\\/aaron-may-chef-boyaaron#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/people\\\/chefs\\\/aaron-may-chef-boyaaron\"},\"author\":{\"name\":\"kbolton\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/people\\\/#\\\/schema\\\/person\\\/8950735b5aff9e8b882a34488c141767\"},\"headline\":\"Aaron May: Chef BoyAARON\",\"datePublished\":\"2012-10-30T16:00:56+00:00\",\"dateModified\":\"2012-12-11T15:50:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/people\\\/chefs\\\/aaron-may-chef-boyaaron\"},\"wordCount\":275,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/people\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/people\\\/chefs\\\/aaron-may-chef-boyaaron#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/people\\\/wp-content\\\/uploads\\\/2012\\\/10\\\/24053752\\\/Aaron-May-21.jpg\",\"keywords\":[\"Featured\"],\"articleSection\":[\"Chefs\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/people\\\/chefs\\\/aaron-may-chef-boyaaron#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/people\\\/chefs\\\/aaron-may-chef-boyaaron\",\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/people\\\/chefs\\\/aaron-may-chef-boyaaron\",\"name\":\"Aaron May: Chef BoyAARON\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/people\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/people\\\/chefs\\\/aaron-may-chef-boyaaron#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/people\\\/chefs\\\/aaron-may-chef-boyaaron#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/people\\\/wp-content\\\/uploads\\\/2012\\\/10\\\/24053752\\\/Aaron-May-21.jpg\",\"datePublished\":\"2012-10-30T16:00:56+00:00\",\"dateModified\":\"2012-12-11T15:50:49+00:00\",\"description\":\"Meet Chef, Aaron May, as he talks about cooking, family and peers and everything in between.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/people\\\/chefs\\\/aaron-may-chef-boyaaron#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/people\\\/chefs\\\/aaron-may-chef-boyaaron\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/people\\\/chefs\\\/aaron-may-chef-boyaaron#primaryimage\",\"url\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/people\\\/wp-content\\\/uploads\\\/2012\\\/10\\\/24053752\\\/Aaron-May-21.jpg\",\"contentUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/people\\\/wp-content\\\/uploads\\\/2012\\\/10\\\/24053752\\\/Aaron-May-21.jpg\",\"width\":385,\"height\":356},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/people\\\/chefs\\\/aaron-may-chef-boyaaron#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/people\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aaron May: Chef BoyAARON\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/people\\\/#website\",\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/people\\\/\",\"name\":\"Trendsetters\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/people\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/people\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/people\\\/#organization\",\"name\":\"AZFoothills.com LLC\",\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/people\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/people\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/people\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/24111316\\\/apple-touch-icon.jpg\",\"contentUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/people\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/24111316\\\/apple-touch-icon.jpg\",\"width\":180,\"height\":180,\"caption\":\"AZFoothills.com LLC\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/people\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/people\\\/#\\\/schema\\\/person\\\/8950735b5aff9e8b882a34488c141767\",\"name\":\"kbolton\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2c77fb4d51b0604f91ee2fb7fccac9e7ddb91f0684e1cf3023c542c9e50a2a19?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2c77fb4d51b0604f91ee2fb7fccac9e7ddb91f0684e1cf3023c542c9e50a2a19?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2c77fb4d51b0604f91ee2fb7fccac9e7ddb91f0684e1cf3023c542c9e50a2a19?s=96&d=mm&r=g\",\"caption\":\"kbolton\"},\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/people\\\/author\\\/kbolton\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aaron May: Chef BoyAARON","description":"Meet Chef, Aaron May, as he talks about cooking, family and peers and everything in between.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.arizonafoothillsmagazine.com\/people\/chefs\/aaron-may-chef-boyaaron","og_locale":"en_US","og_type":"article","og_title":"Aaron May: Chef BoyAARON","og_description":"Meet Chef, Aaron May, as he talks about cooking, family and peers and everything in between.","og_url":"https:\/\/www.arizonafoothillsmagazine.com\/people\/chefs\/aaron-may-chef-boyaaron","og_site_name":"Trendsetters","article_published_time":"2012-10-30T16:00:56+00:00","article_modified_time":"2012-12-11T15:50:49+00:00","og_image":[{"width":385,"height":356,"url":"https:\/\/media.arizonafoothillsmagazine.com\/people\/wp-content\/uploads\/2012\/10\/24053752\/Aaron-May-21.jpg","type":"image\/jpeg"}],"author":"kbolton","twitter_card":"summary_large_image","twitter_misc":{"Written by":"kbolton","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.arizonafoothillsmagazine.com\/people\/chefs\/aaron-may-chef-boyaaron#article","isPartOf":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/people\/chefs\/aaron-may-chef-boyaaron"},"author":{"name":"kbolton","@id":"https:\/\/www.arizonafoothillsmagazine.com\/people\/#\/schema\/person\/8950735b5aff9e8b882a34488c141767"},"headline":"Aaron May: Chef BoyAARON","datePublished":"2012-10-30T16:00:56+00:00","dateModified":"2012-12-11T15:50:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/people\/chefs\/aaron-may-chef-boyaaron"},"wordCount":275,"commentCount":0,"publisher":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/people\/#organization"},"image":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/people\/chefs\/aaron-may-chef-boyaaron#primaryimage"},"thumbnailUrl":"https:\/\/media.arizonafoothillsmagazine.com\/people\/wp-content\/uploads\/2012\/10\/24053752\/Aaron-May-21.jpg","keywords":["Featured"],"articleSection":["Chefs"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.arizonafoothillsmagazine.com\/people\/chefs\/aaron-may-chef-boyaaron#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.arizonafoothillsmagazine.com\/people\/chefs\/aaron-may-chef-boyaaron","url":"https:\/\/www.arizonafoothillsmagazine.com\/people\/chefs\/aaron-may-chef-boyaaron","name":"Aaron May: Chef BoyAARON","isPartOf":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/people\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/people\/chefs\/aaron-may-chef-boyaaron#primaryimage"},"image":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/people\/chefs\/aaron-may-chef-boyaaron#primaryimage"},"thumbnailUrl":"https:\/\/media.arizonafoothillsmagazine.com\/people\/wp-content\/uploads\/2012\/10\/24053752\/Aaron-May-21.jpg","datePublished":"2012-10-30T16:00:56+00:00","dateModified":"2012-12-11T15:50:49+00:00","description":"Meet Chef, Aaron May, as he talks about cooking, family and peers and everything in between.","breadcrumb":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/people\/chefs\/aaron-may-chef-boyaaron#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.arizonafoothillsmagazine.com\/people\/chefs\/aaron-may-chef-boyaaron"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.arizonafoothillsmagazine.com\/people\/chefs\/aaron-may-chef-boyaaron#primaryimage","url":"https:\/\/media.arizonafoothillsmagazine.com\/people\/wp-content\/uploads\/2012\/10\/24053752\/Aaron-May-21.jpg","contentUrl":"https:\/\/media.arizonafoothillsmagazine.com\/people\/wp-content\/uploads\/2012\/10\/24053752\/Aaron-May-21.jpg","width":385,"height":356},{"@type":"BreadcrumbList","@id":"https:\/\/www.arizonafoothillsmagazine.com\/people\/chefs\/aaron-may-chef-boyaaron#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.arizonafoothillsmagazine.com\/people\/"},{"@type":"ListItem","position":2,"name":"Aaron May: Chef BoyAARON"}]},{"@type":"WebSite","@id":"https:\/\/www.arizonafoothillsmagazine.com\/people\/#website","url":"https:\/\/www.arizonafoothillsmagazine.com\/people\/","name":"Trendsetters","description":"","publisher":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/people\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.arizonafoothillsmagazine.com\/people\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.arizonafoothillsmagazine.com\/people\/#organization","name":"AZFoothills.com LLC","url":"https:\/\/www.arizonafoothillsmagazine.com\/people\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.arizonafoothillsmagazine.com\/people\/#\/schema\/logo\/image\/","url":"https:\/\/media.arizonafoothillsmagazine.com\/people\/wp-content\/uploads\/2020\/10\/24111316\/apple-touch-icon.jpg","contentUrl":"https:\/\/media.arizonafoothillsmagazine.com\/people\/wp-content\/uploads\/2020\/10\/24111316\/apple-touch-icon.jpg","width":180,"height":180,"caption":"AZFoothills.com LLC"},"image":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/people\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.arizonafoothillsmagazine.com\/people\/#\/schema\/person\/8950735b5aff9e8b882a34488c141767","name":"kbolton","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/2c77fb4d51b0604f91ee2fb7fccac9e7ddb91f0684e1cf3023c542c9e50a2a19?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2c77fb4d51b0604f91ee2fb7fccac9e7ddb91f0684e1cf3023c542c9e50a2a19?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2c77fb4d51b0604f91ee2fb7fccac9e7ddb91f0684e1cf3023c542c9e50a2a19?s=96&d=mm&r=g","caption":"kbolton"},"url":"https:\/\/www.arizonafoothillsmagazine.com\/people\/author\/kbolton"}]}},"_links":{"self":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/people\/wp-json\/wp\/v2\/posts\/497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/people\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/people\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/people\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/people\/wp-json\/wp\/v2\/comments?post=497"}],"version-history":[{"count":4,"href":"https:\/\/www.arizonafoothillsmagazine.com\/people\/wp-json\/wp\/v2\/posts\/497\/revisions"}],"predecessor-version":[{"id":502,"href":"https:\/\/www.arizonafoothillsmagazine.com\/people\/wp-json\/wp\/v2\/posts\/497\/revisions\/502"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/people\/wp-json\/wp\/v2\/media\/499"}],"wp:attachment":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/people\/wp-json\/wp\/v2\/media?parent=497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/people\/wp-json\/wp\/v2\/categories?post=497"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/people\/wp-json\/wp\/v2\/tags?post=497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}