{"id":7861,"date":"2019-08-08T16:25:39","date_gmt":"2019-08-08T23:25:39","guid":{"rendered":"https:\/\/www.arizonafoothillsmagazine.com\/fitness\/?p=7861"},"modified":"2019-07-25T16:42:25","modified_gmt":"2019-07-25T23:42:25","slug":"travel-essentials-for-a-fit-lifestyle","status":"publish","type":"post","link":"https:\/\/www.arizonafoothillsmagazine.com\/health-and-fitness\/news\/travel-essentials-for-a-fit-lifestyle\/","title":{"rendered":"Travel Essentials for A Fit Lifestyle"},"content":{"rendered":"\r\n<figure class=\"wp-block-image\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"750\"  height=\"500\"  class=\"wp-image-7864 pk-lazyload\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  alt=\"\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 750px) 100vw, 750px\"  data-pk-src=\"https:\/\/www.arizonafoothillsmagazine.com\/fitness\/wp-content\/uploads\/2019\/07\/WOD4TRENT_2019-100-750x500.jpg\"  data-pk-srcset=\"https:\/\/media.arizonafoothillsmagazine.com\/health-and-fitness\/wp-content\/uploads\/2019\/07\/24162511\/WOD4TRENT_2019-100-750x500.jpg 750w, https:\/\/media.arizonafoothillsmagazine.com\/health-and-fitness\/wp-content\/uploads\/2019\/07\/24162511\/WOD4TRENT_2019-100-300x200.jpg 300w, https:\/\/media.arizonafoothillsmagazine.com\/health-and-fitness\/wp-content\/uploads\/2019\/07\/24162511\/WOD4TRENT_2019-100-1024x683.jpg 1024w, https:\/\/media.arizonafoothillsmagazine.com\/health-and-fitness\/wp-content\/uploads\/2019\/07\/24162511\/WOD4TRENT_2019-100-768x512.jpg 768w, https:\/\/media.arizonafoothillsmagazine.com\/health-and-fitness\/wp-content\/uploads\/2019\/07\/24162511\/WOD4TRENT_2019-100-380x253.jpg 380w, https:\/\/media.arizonafoothillsmagazine.com\/health-and-fitness\/wp-content\/uploads\/2019\/07\/24162511\/WOD4TRENT_2019-100-800x533.jpg 800w, https:\/\/media.arizonafoothillsmagazine.com\/health-and-fitness\/wp-content\/uploads\/2019\/07\/24162511\/WOD4TRENT_2019-100-1160x773.jpg 1160w, https:\/\/media.arizonafoothillsmagazine.com\/health-and-fitness\/wp-content\/uploads\/2019\/07\/24162511\/WOD4TRENT_2019-100-80x53.jpg 80w, https:\/\/media.arizonafoothillsmagazine.com\/health-and-fitness\/wp-content\/uploads\/2019\/07\/24162511\/WOD4TRENT_2019-100-620x413.jpg 620w, https:\/\/media.arizonafoothillsmagazine.com\/health-and-fitness\/wp-content\/uploads\/2019\/07\/24162511\/WOD4TRENT_2019-100-850x567.jpg 850w, https:\/\/media.arizonafoothillsmagazine.com\/health-and-fitness\/wp-content\/uploads\/2019\/07\/24162511\/WOD4TRENT_2019-100.jpg 1350w\" >\r\n<figcaption>Never Leave Home Without Your Jump Rope<br \/>Photo by @jweinberg at <a href=\"http:\/\/CrossfitPHX.com\">CrossFit PHX<\/a><\/figcaption>\r\n<\/figure>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">The top 5 things that fit in your carry-on for fitness:<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">1) Lacrosse ball &#8211; great for massage the knots and unlocking tight muscles that get bound up during long periods of sitting during travel<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">2) Jump rope &#8211; great if you&#8217;re in a pinch and have to do something in the hotel room first thing in the morning or before you head to bed<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">3) Tennis Shoes &#8211; you can run anywhere, no matter where you end up. Cardio if FREE.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">4) Foam Roller &#8211; stimulate blood flow to the extremities between flights or in the hotel after a long day of travel and sightseeing<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">5) Mobility Strap &#8211; lengthen tight muscles and increase range of motion that you struggle to get into on your own<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Check out how to pack it all in on instagram:\u00a0<a href=\"https:\/\/www.instagram.com\/p\/BzvmC-XgNoL\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.instagram.com\/p\/BzvmC-XgNoL\/<\/a><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Mycal Anders, MS, CSCS (@coachderz)<\/p>\r\n","protected":false},"excerpt":{"rendered":"The top 5 things that fit in your carry-on for fitness: 1) Lacrosse ball &#8211; great for massage&hellip;\n","protected":false},"author":28,"featured_media":7864,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[62],"tags":[],"class_list":["post-7861","post","type-post","status-publish","format-standard","has-post-thumbnail","category-news","cs-entry","cs-video-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Travel Essentials for A Fit Lifestyle<\/title>\n<meta name=\"description\" content=\"Never Leave Home Without Your Jump RopePhoto by @jweinberg at CrossFit PHX The top 5 things that fit in your carry-on for fitness: 1) Lacrosse ball -\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.arizonafoothillsmagazine.com\/health-and-fitness\/news\/travel-essentials-for-a-fit-lifestyle\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Travel Essentials for A Fit Lifestyle\" \/>\n<meta property=\"og:description\" content=\"Never Leave Home Without Your Jump RopePhoto by @jweinberg at CrossFit PHX The top 5 things that fit in your carry-on for fitness: 1) Lacrosse ball -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.arizonafoothillsmagazine.com\/health-and-fitness\/news\/travel-essentials-for-a-fit-lifestyle\/\" \/>\n<meta property=\"og:site_name\" content=\"Health &amp; Fitness\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-08T23:25:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.arizonafoothillsmagazine.com\/health-and-fitness\/wp-content\/uploads\/2019\/07\/24162511\/WOD4TRENT_2019-100.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1350\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mycal Anders\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/health-and-fitness\\\/news\\\/travel-essentials-for-a-fit-lifestyle\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/health-and-fitness\\\/news\\\/travel-essentials-for-a-fit-lifestyle\\\/\"},\"author\":{\"name\":\"Mycal Anders\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/health-and-fitness\\\/#\\\/schema\\\/person\\\/ae02da003bb55fe5449c6d72435d605d\"},\"headline\":\"Travel Essentials for A Fit Lifestyle\",\"datePublished\":\"2019-08-08T23:25:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/health-and-fitness\\\/news\\\/travel-essentials-for-a-fit-lifestyle\\\/\"},\"wordCount\":161,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/health-and-fitness\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/health-and-fitness\\\/news\\\/travel-essentials-for-a-fit-lifestyle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/health-and-fitness\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/24162511\\\/WOD4TRENT_2019-100.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/health-and-fitness\\\/news\\\/travel-essentials-for-a-fit-lifestyle\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/health-and-fitness\\\/news\\\/travel-essentials-for-a-fit-lifestyle\\\/\",\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/health-and-fitness\\\/news\\\/travel-essentials-for-a-fit-lifestyle\\\/\",\"name\":\"Travel Essentials for A Fit Lifestyle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/health-and-fitness\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/health-and-fitness\\\/news\\\/travel-essentials-for-a-fit-lifestyle\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/health-and-fitness\\\/news\\\/travel-essentials-for-a-fit-lifestyle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/health-and-fitness\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/24162511\\\/WOD4TRENT_2019-100.jpg\",\"datePublished\":\"2019-08-08T23:25:39+00:00\",\"description\":\"Never Leave Home Without Your Jump RopePhoto by @jweinberg at CrossFit PHX The top 5 things that fit in your carry-on for fitness: 1) Lacrosse ball -\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/health-and-fitness\\\/news\\\/travel-essentials-for-a-fit-lifestyle\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/health-and-fitness\\\/news\\\/travel-essentials-for-a-fit-lifestyle\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/health-and-fitness\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/24162511\\\/WOD4TRENT_2019-100.jpg\",\"contentUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/health-and-fitness\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/24162511\\\/WOD4TRENT_2019-100.jpg\",\"width\":1350,\"height\":900},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/health-and-fitness\\\/#website\",\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/health-and-fitness\\\/\",\"name\":\"Health &amp; Fitness\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/health-and-fitness\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/health-and-fitness\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/health-and-fitness\\\/#organization\",\"name\":\"AZFoothills.com LLC\",\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/health-and-fitness\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/health-and-fitness\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/health-and-fitness\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/24163102\\\/apple-touch-icon.jpg\",\"contentUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/health-and-fitness\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/24163102\\\/apple-touch-icon.jpg\",\"width\":180,\"height\":180,\"caption\":\"AZFoothills.com LLC\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/health-and-fitness\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/health-and-fitness\\\/#\\\/schema\\\/person\\\/ae02da003bb55fe5449c6d72435d605d\",\"name\":\"Mycal Anders\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c88de32e0de561c552e17c2a20265d160f44611737b56e707bcfd36e83754eb5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c88de32e0de561c552e17c2a20265d160f44611737b56e707bcfd36e83754eb5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c88de32e0de561c552e17c2a20265d160f44611737b56e707bcfd36e83754eb5?s=96&d=mm&r=g\",\"caption\":\"Mycal Anders\"},\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/health-and-fitness\\\/author\\\/mycal\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Travel Essentials for A Fit Lifestyle","description":"Never Leave Home Without Your Jump RopePhoto by @jweinberg at CrossFit PHX The top 5 things that fit in your carry-on for fitness: 1) Lacrosse ball -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.arizonafoothillsmagazine.com\/health-and-fitness\/news\/travel-essentials-for-a-fit-lifestyle\/","og_locale":"en_US","og_type":"article","og_title":"Travel Essentials for A Fit Lifestyle","og_description":"Never Leave Home Without Your Jump RopePhoto by @jweinberg at CrossFit PHX The top 5 things that fit in your carry-on for fitness: 1) Lacrosse ball -","og_url":"https:\/\/www.arizonafoothillsmagazine.com\/health-and-fitness\/news\/travel-essentials-for-a-fit-lifestyle\/","og_site_name":"Health &amp; Fitness","article_published_time":"2019-08-08T23:25:39+00:00","og_image":[{"width":1350,"height":900,"url":"https:\/\/media.arizonafoothillsmagazine.com\/health-and-fitness\/wp-content\/uploads\/2019\/07\/24162511\/WOD4TRENT_2019-100.jpg","type":"image\/jpeg"}],"author":"Mycal Anders","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.arizonafoothillsmagazine.com\/health-and-fitness\/news\/travel-essentials-for-a-fit-lifestyle\/#article","isPartOf":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/health-and-fitness\/news\/travel-essentials-for-a-fit-lifestyle\/"},"author":{"name":"Mycal Anders","@id":"https:\/\/www.arizonafoothillsmagazine.com\/health-and-fitness\/#\/schema\/person\/ae02da003bb55fe5449c6d72435d605d"},"headline":"Travel Essentials for A Fit Lifestyle","datePublished":"2019-08-08T23:25:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/health-and-fitness\/news\/travel-essentials-for-a-fit-lifestyle\/"},"wordCount":161,"commentCount":0,"publisher":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/health-and-fitness\/#organization"},"image":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/health-and-fitness\/news\/travel-essentials-for-a-fit-lifestyle\/#primaryimage"},"thumbnailUrl":"https:\/\/media.arizonafoothillsmagazine.com\/health-and-fitness\/wp-content\/uploads\/2019\/07\/24162511\/WOD4TRENT_2019-100.jpg","articleSection":["News"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.arizonafoothillsmagazine.com\/health-and-fitness\/news\/travel-essentials-for-a-fit-lifestyle\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.arizonafoothillsmagazine.com\/health-and-fitness\/news\/travel-essentials-for-a-fit-lifestyle\/","url":"https:\/\/www.arizonafoothillsmagazine.com\/health-and-fitness\/news\/travel-essentials-for-a-fit-lifestyle\/","name":"Travel Essentials for A Fit Lifestyle","isPartOf":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/health-and-fitness\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/health-and-fitness\/news\/travel-essentials-for-a-fit-lifestyle\/#primaryimage"},"image":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/health-and-fitness\/news\/travel-essentials-for-a-fit-lifestyle\/#primaryimage"},"thumbnailUrl":"https:\/\/media.arizonafoothillsmagazine.com\/health-and-fitness\/wp-content\/uploads\/2019\/07\/24162511\/WOD4TRENT_2019-100.jpg","datePublished":"2019-08-08T23:25:39+00:00","description":"Never Leave Home Without Your Jump RopePhoto by @jweinberg at CrossFit PHX The top 5 things that fit in your carry-on for fitness: 1) Lacrosse ball -","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.arizonafoothillsmagazine.com\/health-and-fitness\/news\/travel-essentials-for-a-fit-lifestyle\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.arizonafoothillsmagazine.com\/health-and-fitness\/news\/travel-essentials-for-a-fit-lifestyle\/#primaryimage","url":"https:\/\/media.arizonafoothillsmagazine.com\/health-and-fitness\/wp-content\/uploads\/2019\/07\/24162511\/WOD4TRENT_2019-100.jpg","contentUrl":"https:\/\/media.arizonafoothillsmagazine.com\/health-and-fitness\/wp-content\/uploads\/2019\/07\/24162511\/WOD4TRENT_2019-100.jpg","width":1350,"height":900},{"@type":"WebSite","@id":"https:\/\/www.arizonafoothillsmagazine.com\/health-and-fitness\/#website","url":"https:\/\/www.arizonafoothillsmagazine.com\/health-and-fitness\/","name":"Health &amp; Fitness","description":"","publisher":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/health-and-fitness\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.arizonafoothillsmagazine.com\/health-and-fitness\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.arizonafoothillsmagazine.com\/health-and-fitness\/#organization","name":"AZFoothills.com LLC","url":"https:\/\/www.arizonafoothillsmagazine.com\/health-and-fitness\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.arizonafoothillsmagazine.com\/health-and-fitness\/#\/schema\/logo\/image\/","url":"https:\/\/media.arizonafoothillsmagazine.com\/health-and-fitness\/wp-content\/uploads\/2020\/10\/24163102\/apple-touch-icon.jpg","contentUrl":"https:\/\/media.arizonafoothillsmagazine.com\/health-and-fitness\/wp-content\/uploads\/2020\/10\/24163102\/apple-touch-icon.jpg","width":180,"height":180,"caption":"AZFoothills.com LLC"},"image":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/health-and-fitness\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.arizonafoothillsmagazine.com\/health-and-fitness\/#\/schema\/person\/ae02da003bb55fe5449c6d72435d605d","name":"Mycal Anders","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/c88de32e0de561c552e17c2a20265d160f44611737b56e707bcfd36e83754eb5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c88de32e0de561c552e17c2a20265d160f44611737b56e707bcfd36e83754eb5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c88de32e0de561c552e17c2a20265d160f44611737b56e707bcfd36e83754eb5?s=96&d=mm&r=g","caption":"Mycal Anders"},"url":"https:\/\/www.arizonafoothillsmagazine.com\/health-and-fitness\/author\/mycal\/"}]}},"_links":{"self":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/health-and-fitness\/wp-json\/wp\/v2\/posts\/7861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/health-and-fitness\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/health-and-fitness\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/health-and-fitness\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/health-and-fitness\/wp-json\/wp\/v2\/comments?post=7861"}],"version-history":[{"count":3,"href":"https:\/\/www.arizonafoothillsmagazine.com\/health-and-fitness\/wp-json\/wp\/v2\/posts\/7861\/revisions"}],"predecessor-version":[{"id":7870,"href":"https:\/\/www.arizonafoothillsmagazine.com\/health-and-fitness\/wp-json\/wp\/v2\/posts\/7861\/revisions\/7870"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/health-and-fitness\/wp-json\/wp\/v2\/media\/7864"}],"wp:attachment":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/health-and-fitness\/wp-json\/wp\/v2\/media?parent=7861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/health-and-fitness\/wp-json\/wp\/v2\/categories?post=7861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/health-and-fitness\/wp-json\/wp\/v2\/tags?post=7861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}