{"id":1148,"count":3,"description":"","link":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/tag\/performance\/","name":"performance","slug":"performance","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>performance Archives - Nightlife<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"performance Archives - Nightlife\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/tag\/performance\/\" \/>\n<meta property=\"og:site_name\" content=\"Nightlife\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/tag\\\/performance\\\/\",\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/tag\\\/performance\\\/\",\"name\":\"performance Archives - Nightlife\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/#website\"},\"inLanguage\":\"en-US\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/#website\",\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/\",\"name\":\"Nightlife\",\"description\":\"Arizona Nightlife Events, News, Artists and Photos\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/#organization\",\"name\":\"AZFoothills.com LLC\",\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/aznightlife\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/27123536\\\/apple-touch-icon.jpg\",\"contentUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/aznightlife\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/27123536\\\/apple-touch-icon.jpg\",\"width\":180,\"height\":180,\"caption\":\"AZFoothills.com LLC\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"performance Archives - Nightlife","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"performance Archives - Nightlife","og_url":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/tag\/performance\/","og_site_name":"Nightlife","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/tag\/performance\/","url":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/tag\/performance\/","name":"performance Archives - Nightlife","isPartOf":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/#website"},"inLanguage":"en-US"},{"@type":"WebSite","@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/#website","url":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/","name":"Nightlife","description":"Arizona Nightlife Events, News, Artists and Photos","publisher":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/#organization","name":"AZFoothills.com LLC","url":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/#\/schema\/logo\/image\/","url":"https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2020\/10\/27123536\/apple-touch-icon.jpg","contentUrl":"https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2020\/10\/27123536\/apple-touch-icon.jpg","width":180,"height":180,"caption":"AZFoothills.com LLC"},"image":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/wp-json\/wp\/v2\/tags\/1148","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/wp-json\/wp\/v2\/posts?tags=1148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}