{"id":34428,"date":"2019-12-05T12:00:24","date_gmt":"2019-12-05T19:00:24","guid":{"rendered":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/?p=34428"},"modified":"2019-11-21T11:27:39","modified_gmt":"2019-11-21T18:27:39","slug":"behind-the-bar-johncie-thomson-of-thirsty-lion","status":"publish","type":"post","link":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/behind-the-bar-johncie-thomson-of-thirsty-lion\/","title":{"rendered":"Behind the Bar: Johncie Thomson of Thirsty Lion"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"750\"  height=\"962\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  alt=\"\"  class=\"wp-image-34429 pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 750px) 100vw, 750px\"  data-pk-src=\"https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/10\/27120705\/Johncie-Thomson-Marketing-1-750x962.jpg\"  data-pk-srcset=\"https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/10\/27120705\/Johncie-Thomson-Marketing-1-750x962.jpg 750w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/10\/27120705\/Johncie-Thomson-Marketing-1-234x300.jpg 234w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/10\/27120705\/Johncie-Thomson-Marketing-1-798x1024.jpg 798w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/10\/27120705\/Johncie-Thomson-Marketing-1-768x985.jpg 768w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/10\/27120705\/Johncie-Thomson-Marketing-1-1198x1536.jpg 1198w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/10\/27120705\/Johncie-Thomson-Marketing-1-380x487.jpg 380w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/10\/27120705\/Johncie-Thomson-Marketing-1-800x1026.jpg 800w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/10\/27120705\/Johncie-Thomson-Marketing-1-1160x1488.jpg 1160w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/10\/27120705\/Johncie-Thomson-Marketing-1-80x103.jpg 80w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/10\/27120705\/Johncie-Thomson-Marketing-1-62x80.jpg 62w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/10\/27120705\/Johncie-Thomson-Marketing-1-620x795.jpg 620w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/10\/27120705\/Johncie-Thomson-Marketing-1-850x1090.jpg 850w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/10\/27120705\/Johncie-Thomson-Marketing-1-250x321.jpg 250w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/10\/27120705\/Johncie-Thomson-Marketing-1-550x705.jpg 550w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/10\/27120705\/Johncie-Thomson-Marketing-1-140x180.jpg 140w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/10\/27120705\/Johncie-Thomson-Marketing-1-390x500.jpg 390w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/10\/27120705\/Johncie-Thomson-Marketing-1.jpg 1465w\" ><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Name:<\/strong> Johncie Thomson&nbsp; <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Title: <\/strong>Corporate Bar Training Manager for Concept Entertainment (<a href=\"https:\/\/www.thirstyliongastropub.com\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Thirsty Lion (opens in a new tab)\">Thirsty Lion<\/a>)&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Instagram:<\/strong> <a href=\"https:\/\/www.instagram.com\/thirstyliongastropub\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"@thirstyliongastropub (opens in a new tab)\">@thirstyliongastropub<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Find me mixing drinks<\/strong> and training our amazing bar staff at Desert Ridge this winter. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Favorite drink to make:<\/strong> Bourbon Sazerac&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>I\u2019d most like to mix a drink for<\/strong> Larry Fitzgerald.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>If I could have one superpower while working, it\u2019d be<\/strong> to be fast like the Flash, but have it look like a dance.&nbsp; &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>If I were a flavor, I\u2019d be<\/strong> spicy.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>My biggest bartending fail:<\/strong> While cleaning the restaurant for closing, I locked myself out of the building taking out the trash. &nbsp; &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>My top drink and food recommendation to guests:<\/strong> An Old Fashioned with a grilled entr\u00e9e.&nbsp;I enjoy a great dining experience and love to share that passion with others. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>When I\u2019m not working, I enjoy sipping<\/strong> local craft beers or an Old Fashioned.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>My favorite place in town for drinks is<\/strong> Arizona Distilling.<\/p>\n","protected":false},"excerpt":{"rendered":"Go behind the bar with Johncie Thomson, the Corporate Bar Training Manager for Thirsty Lion.\n","protected":false},"author":12,"featured_media":34429,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[4,3],"tags":[1900,139,2823,1124],"class_list":["post-34428","post","type-post","status-publish","format-standard","has-post-thumbnail","category-interviews","category-news","tag-behind-the-bar","tag-featured","tag-johncie-thomson","tag-thirsty-lion","cs-entry","cs-video-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Behind the Bar: Johncie Thomson of Thirsty Lion<\/title>\n<meta name=\"description\" content=\"Go behind the bar with Johncie Thomson, the Corporate Bar Training Manager for Thirsty Lion.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/behind-the-bar-johncie-thomson-of-thirsty-lion\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Behind the Bar: Johncie Thomson of Thirsty Lion\" \/>\n<meta property=\"og:description\" content=\"Go behind the bar with Johncie Thomson, the Corporate Bar Training Manager for Thirsty Lion.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/behind-the-bar-johncie-thomson-of-thirsty-lion\/\" \/>\n<meta property=\"og:site_name\" content=\"Nightlife\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-05T19:00:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/10\/27120705\/Johncie-Thomson-Marketing-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1465\" \/>\n\t<meta property=\"og:image:height\" content=\"1879\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Suzanne Koch\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/behind-the-bar-johncie-thomson-of-thirsty-lion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/behind-the-bar-johncie-thomson-of-thirsty-lion\\\/\"},\"author\":{\"name\":\"Suzanne Koch\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/#\\\/schema\\\/person\\\/d90ed0cccd2e98a875a2884c95b83619\"},\"headline\":\"Behind the Bar: Johncie Thomson of Thirsty Lion\",\"datePublished\":\"2019-12-05T19:00:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/behind-the-bar-johncie-thomson-of-thirsty-lion\\\/\"},\"wordCount\":174,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/behind-the-bar-johncie-thomson-of-thirsty-lion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/aznightlife\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/27120705\\\/Johncie-Thomson-Marketing-1.jpg\",\"keywords\":[\"behind the bar\",\"featured\",\"johncie thomson\",\"thirsty lion\"],\"articleSection\":[\"Artists &amp; Interviews\",\"News\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/behind-the-bar-johncie-thomson-of-thirsty-lion\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/behind-the-bar-johncie-thomson-of-thirsty-lion\\\/\",\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/behind-the-bar-johncie-thomson-of-thirsty-lion\\\/\",\"name\":\"Behind the Bar: Johncie Thomson of Thirsty Lion\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/behind-the-bar-johncie-thomson-of-thirsty-lion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/behind-the-bar-johncie-thomson-of-thirsty-lion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/aznightlife\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/27120705\\\/Johncie-Thomson-Marketing-1.jpg\",\"datePublished\":\"2019-12-05T19:00:24+00:00\",\"description\":\"Go behind the bar with Johncie Thomson, the Corporate Bar Training Manager for Thirsty Lion.\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/behind-the-bar-johncie-thomson-of-thirsty-lion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/behind-the-bar-johncie-thomson-of-thirsty-lion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/aznightlife\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/27120705\\\/Johncie-Thomson-Marketing-1.jpg\",\"contentUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/aznightlife\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/27120705\\\/Johncie-Thomson-Marketing-1.jpg\",\"width\":1465,\"height\":1879},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/#website\",\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/\",\"name\":\"Nightlife\",\"description\":\"Arizona Nightlife Events, News, Artists and Photos\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/#organization\",\"name\":\"AZFoothills.com LLC\",\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/aznightlife\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/27123536\\\/apple-touch-icon.jpg\",\"contentUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/aznightlife\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/27123536\\\/apple-touch-icon.jpg\",\"width\":180,\"height\":180,\"caption\":\"AZFoothills.com LLC\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/#\\\/schema\\\/person\\\/d90ed0cccd2e98a875a2884c95b83619\",\"name\":\"Suzanne Koch\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/80deb7187c358b0b0ac8410aa9d779c438905837df07d79d2e1616f13867b51a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/80deb7187c358b0b0ac8410aa9d779c438905837df07d79d2e1616f13867b51a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/80deb7187c358b0b0ac8410aa9d779c438905837df07d79d2e1616f13867b51a?s=96&d=mm&r=g\",\"caption\":\"Suzanne Koch\"},\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/author\\\/suzanne\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Behind the Bar: Johncie Thomson of Thirsty Lion","description":"Go behind the bar with Johncie Thomson, the Corporate Bar Training Manager for Thirsty Lion.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/behind-the-bar-johncie-thomson-of-thirsty-lion\/","og_locale":"en_US","og_type":"article","og_title":"Behind the Bar: Johncie Thomson of Thirsty Lion","og_description":"Go behind the bar with Johncie Thomson, the Corporate Bar Training Manager for Thirsty Lion.","og_url":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/behind-the-bar-johncie-thomson-of-thirsty-lion\/","og_site_name":"Nightlife","article_published_time":"2019-12-05T19:00:24+00:00","og_image":[{"width":1465,"height":1879,"url":"https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/10\/27120705\/Johncie-Thomson-Marketing-1.jpg","type":"image\/jpeg"}],"author":"Suzanne Koch","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/behind-the-bar-johncie-thomson-of-thirsty-lion\/#article","isPartOf":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/behind-the-bar-johncie-thomson-of-thirsty-lion\/"},"author":{"name":"Suzanne Koch","@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/#\/schema\/person\/d90ed0cccd2e98a875a2884c95b83619"},"headline":"Behind the Bar: Johncie Thomson of Thirsty Lion","datePublished":"2019-12-05T19:00:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/behind-the-bar-johncie-thomson-of-thirsty-lion\/"},"wordCount":174,"commentCount":0,"publisher":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/#organization"},"image":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/behind-the-bar-johncie-thomson-of-thirsty-lion\/#primaryimage"},"thumbnailUrl":"https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/10\/27120705\/Johncie-Thomson-Marketing-1.jpg","keywords":["behind the bar","featured","johncie thomson","thirsty lion"],"articleSection":["Artists &amp; Interviews","News"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/behind-the-bar-johncie-thomson-of-thirsty-lion\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/behind-the-bar-johncie-thomson-of-thirsty-lion\/","url":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/behind-the-bar-johncie-thomson-of-thirsty-lion\/","name":"Behind the Bar: Johncie Thomson of Thirsty Lion","isPartOf":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/behind-the-bar-johncie-thomson-of-thirsty-lion\/#primaryimage"},"image":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/behind-the-bar-johncie-thomson-of-thirsty-lion\/#primaryimage"},"thumbnailUrl":"https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/10\/27120705\/Johncie-Thomson-Marketing-1.jpg","datePublished":"2019-12-05T19:00:24+00:00","description":"Go behind the bar with Johncie Thomson, the Corporate Bar Training Manager for Thirsty Lion.","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/behind-the-bar-johncie-thomson-of-thirsty-lion\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/behind-the-bar-johncie-thomson-of-thirsty-lion\/#primaryimage","url":"https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/10\/27120705\/Johncie-Thomson-Marketing-1.jpg","contentUrl":"https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/10\/27120705\/Johncie-Thomson-Marketing-1.jpg","width":1465,"height":1879},{"@type":"WebSite","@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/#website","url":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/","name":"Nightlife","description":"Arizona Nightlife Events, News, Artists and Photos","publisher":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/#organization","name":"AZFoothills.com LLC","url":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/#\/schema\/logo\/image\/","url":"https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2020\/10\/27123536\/apple-touch-icon.jpg","contentUrl":"https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2020\/10\/27123536\/apple-touch-icon.jpg","width":180,"height":180,"caption":"AZFoothills.com LLC"},"image":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/#\/schema\/person\/d90ed0cccd2e98a875a2884c95b83619","name":"Suzanne Koch","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/80deb7187c358b0b0ac8410aa9d779c438905837df07d79d2e1616f13867b51a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/80deb7187c358b0b0ac8410aa9d779c438905837df07d79d2e1616f13867b51a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/80deb7187c358b0b0ac8410aa9d779c438905837df07d79d2e1616f13867b51a?s=96&d=mm&r=g","caption":"Suzanne Koch"},"url":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/author\/suzanne\/"}]}},"_links":{"self":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/wp-json\/wp\/v2\/posts\/34428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/wp-json\/wp\/v2\/comments?post=34428"}],"version-history":[{"count":5,"href":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/wp-json\/wp\/v2\/posts\/34428\/revisions"}],"predecessor-version":[{"id":34540,"href":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/wp-json\/wp\/v2\/posts\/34428\/revisions\/34540"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/wp-json\/wp\/v2\/media\/34429"}],"wp:attachment":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/wp-json\/wp\/v2\/media?parent=34428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/wp-json\/wp\/v2\/categories?post=34428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/wp-json\/wp\/v2\/tags?post=34428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}