{"id":33768,"date":"2019-05-07T09:00:15","date_gmt":"2019-05-07T16:00:15","guid":{"rendered":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/?p=33768"},"modified":"2019-05-01T10:18:19","modified_gmt":"2019-05-01T17:18:19","slug":"caribbean-inspired-cocktails-debut-at-blue-hound-kitchen","status":"publish","type":"post","link":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/caribbean-inspired-cocktails-debut-at-blue-hound-kitchen\/","title":{"rendered":"Caribbean-Inspired Cocktails Debut at Blue Hound Kitchen"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><a rel=\"noreferrer noopener\" aria-label=\"Blue Hound Kitchen &amp; Cocktails (opens in a new tab)\" href=\"https:\/\/bluehoundkitchen.com\/\" target=\"_blank\">Blue Hound Kitchen &amp; Cocktails<\/a> is getting a taste of the island life with its new cocktail menu from head bartender Phil Clark. Debuting 16 new tropical cocktails, the menu will feature creations inspired by the sweet and savory flavors of Jamaican cuisine with a desert twist, incorporating ingredients like house-made Mountain Dew shrub, Aperol and peach. Perfect for summer, the new sips will be light and refreshing.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"750\"  height=\"1000\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  alt=\"\"  class=\"wp-image-33769 pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 750px) 100vw, 750px\"  data-pk-src=\"https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/04\/27115133\/Blue-Hound_Tropical-Ice-Age-750x1000.jpg\"  data-pk-srcset=\"https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/04\/27115133\/Blue-Hound_Tropical-Ice-Age-750x1000.jpg 750w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/04\/27115133\/Blue-Hound_Tropical-Ice-Age-225x300.jpg 225w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/04\/27115133\/Blue-Hound_Tropical-Ice-Age-768x1024.jpg 768w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/04\/27115133\/Blue-Hound_Tropical-Ice-Age-1152x1536.jpg 1152w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/04\/27115133\/Blue-Hound_Tropical-Ice-Age-1536x2048.jpg 1536w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/04\/27115133\/Blue-Hound_Tropical-Ice-Age-380x507.jpg 380w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/04\/27115133\/Blue-Hound_Tropical-Ice-Age-800x1067.jpg 800w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/04\/27115133\/Blue-Hound_Tropical-Ice-Age-1160x1547.jpg 1160w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/04\/27115133\/Blue-Hound_Tropical-Ice-Age-80x107.jpg 80w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/04\/27115133\/Blue-Hound_Tropical-Ice-Age-60x80.jpg 60w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/04\/27115133\/Blue-Hound_Tropical-Ice-Age-620x827.jpg 620w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/04\/27115133\/Blue-Hound_Tropical-Ice-Age-850x1133.jpg 850w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/04\/27115133\/Blue-Hound_Tropical-Ice-Age-250x333.jpg 250w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/04\/27115133\/Blue-Hound_Tropical-Ice-Age-550x733.jpg 550w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/04\/27115133\/Blue-Hound_Tropical-Ice-Age-135x180.jpg 135w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/04\/27115133\/Blue-Hound_Tropical-Ice-Age-375x500.jpg 375w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/04\/27115133\/Blue-Hound_Tropical-Ice-Age.jpg 1815w\" ><figcaption>Tropical Ice Age<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Some standouts on the spring cocktail menu include:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Jamaican Getaway<\/strong>, inspired by Derek Brown with Cynar 70, Overproof Jamaican Rum, Angostura, demerara sugar, and lime<\/li><li><strong>Paper Tiger<\/strong>&nbsp;by Kayla Szeliga with Campari, Proper No. Twelve Irish Whiskey, house lime cordial, hibiscus and egg white<\/li><li><strong>Bitter Enthusiast<\/strong>&nbsp;by Derek Mattson with Meletti Amaro, Akashi Japanese Whisky, banana, chocolate bitters and expressed orange<\/li><li><strong>Frost on Windowpane<\/strong>&nbsp;by Jimmy Pederson with Absolute Elyx Vodka, pear liqueur, pinot grigio syrup, lime, soda and sage<\/li><li><strong>Tropical Ice Age<\/strong>&nbsp;by Mike Mailloux with El Dorado Rum, Banks Rum, banana, cacao, cinnamon, lime and pineapple<\/li><li><strong>Dew the Mezcal<\/strong>&nbsp;by Kayla Szeliga with Del Maguey Vida Mezcal, mountain dew shrub, yellow chartreuse, orgeat and rhubarb<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Not only is the bar program being reinvigorated for summer, Executive Chef Dushyant Singh&#8217;s new lunch menu focuses on using undiscovered flavors, seasonal ingredients and contemporary techniques. The menu offers New-American cuisine taking a more sophisticated approach to classic warm-weather dishes like hot dogs, fresh salads and protein-packed bowls.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">For more information, visit: <a href=\"https:\/\/bluehoundkitchen.com\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (opens in a new tab)\">bluehoundkitchen.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"Debuting 16 new tropical cocktails, the menu will feature creations inspired by the sweet and savory flavors of Jamaican cuisine with a twist.\n","protected":false},"author":12,"featured_media":33769,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[1671,3],"tags":[1007,139],"class_list":["post-33768","post","type-post","status-publish","format-standard","has-post-thumbnail","category-events","category-news","tag-blue-hound-kitchen-and-cocktails","tag-featured","cs-entry","cs-video-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Caribbean-Inspired Cocktails Debut at Blue Hound Kitchen<\/title>\n<meta name=\"description\" content=\"Debuting 16 new tropical cocktails, the menu will feature creations inspired by the sweet and savory flavors of Jamaican cuisine with a twist.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/caribbean-inspired-cocktails-debut-at-blue-hound-kitchen\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Caribbean-Inspired Cocktails Debut at Blue Hound Kitchen\" \/>\n<meta property=\"og:description\" content=\"Debuting 16 new tropical cocktails, the menu will feature creations inspired by the sweet and savory flavors of Jamaican cuisine with a twist.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/caribbean-inspired-cocktails-debut-at-blue-hound-kitchen\/\" \/>\n<meta property=\"og:site_name\" content=\"Nightlife\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-07T16:00:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/04\/27115133\/Blue-Hound_Tropical-Ice-Age.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1815\" \/>\n\t<meta property=\"og:image:height\" content=\"2420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Suzanne Koch\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/caribbean-inspired-cocktails-debut-at-blue-hound-kitchen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/caribbean-inspired-cocktails-debut-at-blue-hound-kitchen\\\/\"},\"author\":{\"name\":\"Suzanne Koch\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/#\\\/schema\\\/person\\\/d90ed0cccd2e98a875a2884c95b83619\"},\"headline\":\"Caribbean-Inspired Cocktails Debut at Blue Hound Kitchen\",\"datePublished\":\"2019-05-07T16:00:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/caribbean-inspired-cocktails-debut-at-blue-hound-kitchen\\\/\"},\"wordCount\":254,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/caribbean-inspired-cocktails-debut-at-blue-hound-kitchen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/aznightlife\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/27115133\\\/Blue-Hound_Tropical-Ice-Age.jpg\",\"keywords\":[\"Blue Hound Kitchen and Cocktails\",\"featured\"],\"articleSection\":[\"Events\",\"News\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/caribbean-inspired-cocktails-debut-at-blue-hound-kitchen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/caribbean-inspired-cocktails-debut-at-blue-hound-kitchen\\\/\",\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/caribbean-inspired-cocktails-debut-at-blue-hound-kitchen\\\/\",\"name\":\"Caribbean-Inspired Cocktails Debut at Blue Hound Kitchen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/caribbean-inspired-cocktails-debut-at-blue-hound-kitchen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/caribbean-inspired-cocktails-debut-at-blue-hound-kitchen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/aznightlife\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/27115133\\\/Blue-Hound_Tropical-Ice-Age.jpg\",\"datePublished\":\"2019-05-07T16:00:15+00:00\",\"description\":\"Debuting 16 new tropical cocktails, the menu will feature creations inspired by the sweet and savory flavors of Jamaican cuisine with a twist.\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/caribbean-inspired-cocktails-debut-at-blue-hound-kitchen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/caribbean-inspired-cocktails-debut-at-blue-hound-kitchen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/aznightlife\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/27115133\\\/Blue-Hound_Tropical-Ice-Age.jpg\",\"contentUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/aznightlife\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/27115133\\\/Blue-Hound_Tropical-Ice-Age.jpg\",\"width\":1815,\"height\":2420,\"caption\":\"Tropical Ice Age\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/#website\",\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/\",\"name\":\"Nightlife\",\"description\":\"Arizona Nightlife Events, News, Artists and Photos\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/#organization\",\"name\":\"AZFoothills.com LLC\",\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/aznightlife\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/27123536\\\/apple-touch-icon.jpg\",\"contentUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/aznightlife\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/27123536\\\/apple-touch-icon.jpg\",\"width\":180,\"height\":180,\"caption\":\"AZFoothills.com LLC\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/#\\\/schema\\\/person\\\/d90ed0cccd2e98a875a2884c95b83619\",\"name\":\"Suzanne Koch\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/80deb7187c358b0b0ac8410aa9d779c438905837df07d79d2e1616f13867b51a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/80deb7187c358b0b0ac8410aa9d779c438905837df07d79d2e1616f13867b51a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/80deb7187c358b0b0ac8410aa9d779c438905837df07d79d2e1616f13867b51a?s=96&d=mm&r=g\",\"caption\":\"Suzanne Koch\"},\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/author\\\/suzanne\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Caribbean-Inspired Cocktails Debut at Blue Hound Kitchen","description":"Debuting 16 new tropical cocktails, the menu will feature creations inspired by the sweet and savory flavors of Jamaican cuisine with a twist.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/caribbean-inspired-cocktails-debut-at-blue-hound-kitchen\/","og_locale":"en_US","og_type":"article","og_title":"Caribbean-Inspired Cocktails Debut at Blue Hound Kitchen","og_description":"Debuting 16 new tropical cocktails, the menu will feature creations inspired by the sweet and savory flavors of Jamaican cuisine with a twist.","og_url":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/caribbean-inspired-cocktails-debut-at-blue-hound-kitchen\/","og_site_name":"Nightlife","article_published_time":"2019-05-07T16:00:15+00:00","og_image":[{"width":1815,"height":2420,"url":"https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/04\/27115133\/Blue-Hound_Tropical-Ice-Age.jpg","type":"image\/jpeg"}],"author":"Suzanne Koch","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/caribbean-inspired-cocktails-debut-at-blue-hound-kitchen\/#article","isPartOf":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/caribbean-inspired-cocktails-debut-at-blue-hound-kitchen\/"},"author":{"name":"Suzanne Koch","@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/#\/schema\/person\/d90ed0cccd2e98a875a2884c95b83619"},"headline":"Caribbean-Inspired Cocktails Debut at Blue Hound Kitchen","datePublished":"2019-05-07T16:00:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/caribbean-inspired-cocktails-debut-at-blue-hound-kitchen\/"},"wordCount":254,"commentCount":0,"publisher":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/#organization"},"image":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/caribbean-inspired-cocktails-debut-at-blue-hound-kitchen\/#primaryimage"},"thumbnailUrl":"https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/04\/27115133\/Blue-Hound_Tropical-Ice-Age.jpg","keywords":["Blue Hound Kitchen and Cocktails","featured"],"articleSection":["Events","News"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/caribbean-inspired-cocktails-debut-at-blue-hound-kitchen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/caribbean-inspired-cocktails-debut-at-blue-hound-kitchen\/","url":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/caribbean-inspired-cocktails-debut-at-blue-hound-kitchen\/","name":"Caribbean-Inspired Cocktails Debut at Blue Hound Kitchen","isPartOf":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/caribbean-inspired-cocktails-debut-at-blue-hound-kitchen\/#primaryimage"},"image":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/caribbean-inspired-cocktails-debut-at-blue-hound-kitchen\/#primaryimage"},"thumbnailUrl":"https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/04\/27115133\/Blue-Hound_Tropical-Ice-Age.jpg","datePublished":"2019-05-07T16:00:15+00:00","description":"Debuting 16 new tropical cocktails, the menu will feature creations inspired by the sweet and savory flavors of Jamaican cuisine with a twist.","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/caribbean-inspired-cocktails-debut-at-blue-hound-kitchen\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/caribbean-inspired-cocktails-debut-at-blue-hound-kitchen\/#primaryimage","url":"https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/04\/27115133\/Blue-Hound_Tropical-Ice-Age.jpg","contentUrl":"https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2019\/04\/27115133\/Blue-Hound_Tropical-Ice-Age.jpg","width":1815,"height":2420,"caption":"Tropical Ice Age"},{"@type":"WebSite","@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/#website","url":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/","name":"Nightlife","description":"Arizona Nightlife Events, News, Artists and Photos","publisher":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/#organization","name":"AZFoothills.com LLC","url":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/#\/schema\/logo\/image\/","url":"https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2020\/10\/27123536\/apple-touch-icon.jpg","contentUrl":"https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2020\/10\/27123536\/apple-touch-icon.jpg","width":180,"height":180,"caption":"AZFoothills.com LLC"},"image":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/#\/schema\/person\/d90ed0cccd2e98a875a2884c95b83619","name":"Suzanne Koch","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/80deb7187c358b0b0ac8410aa9d779c438905837df07d79d2e1616f13867b51a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/80deb7187c358b0b0ac8410aa9d779c438905837df07d79d2e1616f13867b51a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/80deb7187c358b0b0ac8410aa9d779c438905837df07d79d2e1616f13867b51a?s=96&d=mm&r=g","caption":"Suzanne Koch"},"url":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/author\/suzanne\/"}]}},"_links":{"self":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/wp-json\/wp\/v2\/posts\/33768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/wp-json\/wp\/v2\/comments?post=33768"}],"version-history":[{"count":4,"href":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/wp-json\/wp\/v2\/posts\/33768\/revisions"}],"predecessor-version":[{"id":33773,"href":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/wp-json\/wp\/v2\/posts\/33768\/revisions\/33773"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/wp-json\/wp\/v2\/media\/33769"}],"wp:attachment":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/wp-json\/wp\/v2\/media?parent=33768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/wp-json\/wp\/v2\/categories?post=33768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/wp-json\/wp\/v2\/tags?post=33768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}