{"id":26443,"date":"2014-06-18T10:35:14","date_gmt":"2014-06-18T17:35:14","guid":{"rendered":"http:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/?p=26443"},"modified":"2014-06-18T13:58:58","modified_gmt":"2014-06-18T20:58:58","slug":"brazzabelle-perform-maya-interview","status":"publish","type":"post","link":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/brazzabelle-perform-maya-interview\/","title":{"rendered":"Brazzabelle to Perform at Maya: Interview"},"content":{"rendered":"<p><a href=\"https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2014\/06\/27062056\/1480716_10152746498271002_1234820276_n.jpg\"><img  loading=\"lazy\"  decoding=\"async\"  class=\"alignnone  wp-image-26444 aligncenter pk-lazyload\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  alt=\"1480716_10152746498271002_1234820276_n\"  width=\"566\"  height=\"472\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 566px) 100vw, 566px\"  data-pk-src=\"https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2014\/06\/27062056\/1480716_10152746498271002_1234820276_n.jpg\"  data-pk-srcset=\"https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2014\/06\/27062056\/1480716_10152746498271002_1234820276_n.jpg 781w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2014\/06\/27062056\/1480716_10152746498271002_1234820276_n-300x250.jpg 300w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2014\/06\/27062056\/1480716_10152746498271002_1234820276_n-768x640.jpg 768w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2014\/06\/27062056\/1480716_10152746498271002_1234820276_n-380x317.jpg 380w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2014\/06\/27062056\/1480716_10152746498271002_1234820276_n-80x67.jpg 80w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2014\/06\/27062056\/1480716_10152746498271002_1234820276_n-750x625.jpg 750w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2014\/06\/27062056\/1480716_10152746498271002_1234820276_n-620x517.jpg 620w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2014\/06\/27062056\/1480716_10152746498271002_1234820276_n-250x208.jpg 250w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2014\/06\/27062056\/1480716_10152746498271002_1234820276_n-550x458.jpg 550w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2014\/06\/27062056\/1480716_10152746498271002_1234820276_n-216x180.jpg 216w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2014\/06\/27062056\/1480716_10152746498271002_1234820276_n-360x300.jpg 360w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2014\/06\/27062056\/1480716_10152746498271002_1234820276_n-600x500.jpg 600w\" ><\/a><\/p>\n<p>Hot electro music DJ will return to Maya Day + Nightclub on Friday, June 27 at 9 p.m. \u00a0 <span style=\"color: #222222;\">Brittney Marie Bowles, known for her stage name\u00a0<\/span>Brazzabelle, is an Arizona native house music DJ, record producer and remixer based out of Los Angeles.<\/p>\n<p>Featured below is the Haddaway &#8220;What Is Love&#8221; remix by Brazzabelle.<\/p>\n[youtube id=&#8221;2Fi51RiUMYs&#8221; width=&#8221;600&#8243; height=&#8221;350&#8243;]\n<p>AZ Foothills got the chance to talk to Brazzabelle about her upcoming concert at Maya, along with her involvement in the music industry. \u00a0Check out what she had to say below!<\/p>\n<p><strong>AFM- How did you come up with the name Brazzabelle?<\/strong><\/p>\n<p><span style=\"color: #222222;\">It\u2019s based of the capital of the Congo which is Brazzaville, and we thought of it because my friends DJ name is Congorock.<\/span><\/p>\n<p><strong>AFM-\u00a0How did you get involved in the music industry?<\/strong><\/p>\n<p>I\u2019ve just always loved music, so I wanted to create music with the songs I loved so much. \u00a0When I was 14 I started creating my own tracks.. I didn\u2019t really get my foot in the door till I played club gigs when I was 21.<\/p>\n<p><strong>AFM-\u00a0How would you describe your sound to those who haven\u2019t heard it?<\/strong><\/p>\n<p>It\u2019s kind of like a mix of hard electro, hip hop and world sounds.. kind of exotic..latin drums.. definitely a mix!<\/p>\n<p><strong>AFM-\u00a0Which song are you most proud of?<\/strong><\/p>\n<p>I\u2019m really proud of all my songs. \u00a0Probably my most fun one that everyone likes is Haddaway &#8220;What Is Love (Remix).&#8221;<\/p>\n<p><strong>AFM- How does it feel to come and perform in Arizona?<\/strong><\/p>\n<p>It\u2019s definitely really cool because I grew up in Arizona. \u00a0I left for school when I was 18 and never got to party in Old Town. \u00a0Now, I get to come back and experience it!<\/p>\n<p><strong>AFM- Aside from performing, what is your favorite thing to do whenever you return to Arizona.<\/strong><\/p>\n<p>I definitely love going golfing, hanging out by the pool and shopping in Scottsdale.<\/p>\n<p><strong>AFM- Where did you go to school?<\/strong><\/p>\n<p>Cactus Shadows High School. \u00a0I also went to CU Boulder and also U of A for my Junior and Senior year.<\/p>\n<p><strong>AFM-\u00a0Which other artists have been your inspiration?<\/strong><\/p>\n<p>I\u2019ve been inspired by so many different artists growing up. \u00a0A few of these artists are ATB and 4 Strings.<\/p>\n<p><strong>AFM-\u00a0What would you say has been your biggest break so far?<\/strong><\/p>\n<p>Probably when I opened for Martin Solveig. \u00a0After opening for him, he asked me to open on other tour dates. He\u2019s been an awesome mentor!<\/p>\n<p><strong>AFM- What is your plan for the future? Goals?<\/strong><\/p>\n<p>To win a grammy.<\/p>\n<p><strong>AFM- What are you expecting on Friday?<\/strong><\/p>\n<p>I\u2019m excited to see what it\u2019s like at night life. \u00a0I know Scottsdale knows how to party, so I\u2019m expecting it to be really fun!<\/p>\n<p><strong>AFM-\u00a0If you could say anything to your Arizona fan base, what would it be?<\/strong><strong>\u00a0<\/strong><\/p>\n<p>Get ready to party on Friday!<\/p>\n<p>For additional information on Brazzabelle and her performance at Maya Day + Nightclub, visit Maya&#8217;s <a href=\"http:\/\/mayaclubaz.com\/events\/brazzabelle\/\">website<\/a>.<\/p>\n<p><a href=\"https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2014\/06\/27062059\/1782058_10153168356901002_8902307808022739245_n.jpg\"><img  loading=\"lazy\"  decoding=\"async\"  class=\"alignnone  wp-image-26445 aligncenter pk-lazyload\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  alt=\"1782058_10153168356901002_8902307808022739245_n\"  width=\"612\"  height=\"407\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 612px) 100vw, 612px\"  data-pk-src=\"https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2014\/06\/27062059\/1782058_10153168356901002_8902307808022739245_n.jpg\"  data-pk-srcset=\"https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2014\/06\/27062059\/1782058_10153168356901002_8902307808022739245_n.jpg 960w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2014\/06\/27062059\/1782058_10153168356901002_8902307808022739245_n-300x200.jpg 300w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2014\/06\/27062059\/1782058_10153168356901002_8902307808022739245_n-768x511.jpg 768w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2014\/06\/27062059\/1782058_10153168356901002_8902307808022739245_n-380x253.jpg 380w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2014\/06\/27062059\/1782058_10153168356901002_8902307808022739245_n-800x533.jpg 800w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2014\/06\/27062059\/1782058_10153168356901002_8902307808022739245_n-80x53.jpg 80w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2014\/06\/27062059\/1782058_10153168356901002_8902307808022739245_n-750x499.jpg 750w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2014\/06\/27062059\/1782058_10153168356901002_8902307808022739245_n-620x413.jpg 620w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2014\/06\/27062059\/1782058_10153168356901002_8902307808022739245_n-850x566.jpg 850w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2014\/06\/27062059\/1782058_10153168356901002_8902307808022739245_n-250x166.jpg 250w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2014\/06\/27062059\/1782058_10153168356901002_8902307808022739245_n-550x366.jpg 550w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2014\/06\/27062059\/1782058_10153168356901002_8902307808022739245_n-270x180.jpg 270w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2014\/06\/27062059\/1782058_10153168356901002_8902307808022739245_n-451x300.jpg 451w, https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2014\/06\/27062059\/1782058_10153168356901002_8902307808022739245_n-751x500.jpg 751w\" ><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"Hot electro music DJ will return to Maya Day + Nightclub on Friday, June 27 at 9 p.m.&hellip;\n","protected":false},"author":8,"featured_media":26444,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[4],"tags":[913,916,914,915,139,910,528,911,912],"class_list":["post-26443","post","type-post","status-publish","format-standard","has-post-thumbnail","category-interviews","tag-brazzabelle","tag-brazzabelle-az-concert","tag-brazzabelle-in-arizona","tag-brazzabelle-maya","tag-featured","tag-maya-az","tag-maya-day-nightclub","tag-maya-dayclub","tag-maya-nightclub","cs-entry","cs-video-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Brazzabelle to Perform at Maya: Interview<\/title>\n<meta name=\"description\" content=\"Hot electro music DJ will return to Maya Day + Nightclub on Friday, June 27 at 9 p.m. \u00a0 Brittney Marie Bowles, known for her stage name\u00a0Brazzabelle, is an\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/brazzabelle-perform-maya-interview\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Brazzabelle to Perform at Maya: Interview\" \/>\n<meta property=\"og:description\" content=\"Hot electro music DJ will return to Maya Day + Nightclub on Friday, June 27 at 9 p.m. \u00a0 Brittney Marie Bowles, known for her stage name\u00a0Brazzabelle, is an\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/brazzabelle-perform-maya-interview\/\" \/>\n<meta property=\"og:site_name\" content=\"Nightlife\" \/>\n<meta property=\"article:published_time\" content=\"2014-06-18T17:35:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-06-18T20:58:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2014\/06\/27062056\/1480716_10152746498271002_1234820276_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"781\" \/>\n\t<meta property=\"og:image:height\" content=\"651\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Caitie Andreen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/brazzabelle-perform-maya-interview\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/brazzabelle-perform-maya-interview\\\/\"},\"author\":{\"name\":\"Caitie Andreen\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/#\\\/schema\\\/person\\\/f3fd293f90fa601e4a8fa8818beaf4fb\"},\"headline\":\"Brazzabelle to Perform at Maya: Interview\",\"datePublished\":\"2014-06-18T17:35:14+00:00\",\"dateModified\":\"2014-06-18T20:58:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/brazzabelle-perform-maya-interview\\\/\"},\"wordCount\":507,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/brazzabelle-perform-maya-interview\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/aznightlife\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/27062056\\\/1480716_10152746498271002_1234820276_n.jpg\",\"keywords\":[\"brazzabelle\",\"brazzabelle az concert\",\"brazzabelle in arizona\",\"brazzabelle maya\",\"featured\",\"maya az\",\"Maya Day &amp; Nightclub\",\"maya dayclub\",\"maya nightclub\"],\"articleSection\":[\"Artists &amp; Interviews\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/brazzabelle-perform-maya-interview\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/brazzabelle-perform-maya-interview\\\/\",\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/brazzabelle-perform-maya-interview\\\/\",\"name\":\"Brazzabelle to Perform at Maya: Interview\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/brazzabelle-perform-maya-interview\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/brazzabelle-perform-maya-interview\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/aznightlife\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/27062056\\\/1480716_10152746498271002_1234820276_n.jpg\",\"datePublished\":\"2014-06-18T17:35:14+00:00\",\"dateModified\":\"2014-06-18T20:58:58+00:00\",\"description\":\"Hot electro music DJ will return to Maya Day + Nightclub on Friday, June 27 at 9 p.m. \u00a0 Brittney Marie Bowles, known for her stage name\u00a0Brazzabelle, is an\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/brazzabelle-perform-maya-interview\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/brazzabelle-perform-maya-interview\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/aznightlife\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/27062056\\\/1480716_10152746498271002_1234820276_n.jpg\",\"contentUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/aznightlife\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/27062056\\\/1480716_10152746498271002_1234820276_n.jpg\",\"width\":781,\"height\":651},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/#website\",\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/\",\"name\":\"Nightlife\",\"description\":\"Arizona Nightlife Events, News, Artists and Photos\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/#organization\",\"name\":\"AZFoothills.com LLC\",\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/aznightlife\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/27123536\\\/apple-touch-icon.jpg\",\"contentUrl\":\"https:\\\/\\\/media.arizonafoothillsmagazine.com\\\/aznightlife\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/27123536\\\/apple-touch-icon.jpg\",\"width\":180,\"height\":180,\"caption\":\"AZFoothills.com LLC\"},\"image\":{\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/#\\\/schema\\\/person\\\/f3fd293f90fa601e4a8fa8818beaf4fb\",\"name\":\"Caitie Andreen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01977f29c813ff3684a09aaa2c62964f23e2d8ea10be55b0900c7f9356c28d3d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01977f29c813ff3684a09aaa2c62964f23e2d8ea10be55b0900c7f9356c28d3d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01977f29c813ff3684a09aaa2c62964f23e2d8ea10be55b0900c7f9356c28d3d?s=96&d=mm&r=g\",\"caption\":\"Caitie Andreen\"},\"url\":\"https:\\\/\\\/www.arizonafoothillsmagazine.com\\\/aznightlife\\\/author\\\/caitie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Brazzabelle to Perform at Maya: Interview","description":"Hot electro music DJ will return to Maya Day + Nightclub on Friday, June 27 at 9 p.m. \u00a0 Brittney Marie Bowles, known for her stage name\u00a0Brazzabelle, is an","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/brazzabelle-perform-maya-interview\/","og_locale":"en_US","og_type":"article","og_title":"Brazzabelle to Perform at Maya: Interview","og_description":"Hot electro music DJ will return to Maya Day + Nightclub on Friday, June 27 at 9 p.m. \u00a0 Brittney Marie Bowles, known for her stage name\u00a0Brazzabelle, is an","og_url":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/brazzabelle-perform-maya-interview\/","og_site_name":"Nightlife","article_published_time":"2014-06-18T17:35:14+00:00","article_modified_time":"2014-06-18T20:58:58+00:00","og_image":[{"width":781,"height":651,"url":"https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2014\/06\/27062056\/1480716_10152746498271002_1234820276_n.jpg","type":"image\/jpeg"}],"author":"Caitie Andreen","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/brazzabelle-perform-maya-interview\/#article","isPartOf":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/brazzabelle-perform-maya-interview\/"},"author":{"name":"Caitie Andreen","@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/#\/schema\/person\/f3fd293f90fa601e4a8fa8818beaf4fb"},"headline":"Brazzabelle to Perform at Maya: Interview","datePublished":"2014-06-18T17:35:14+00:00","dateModified":"2014-06-18T20:58:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/brazzabelle-perform-maya-interview\/"},"wordCount":507,"commentCount":0,"publisher":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/#organization"},"image":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/brazzabelle-perform-maya-interview\/#primaryimage"},"thumbnailUrl":"https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2014\/06\/27062056\/1480716_10152746498271002_1234820276_n.jpg","keywords":["brazzabelle","brazzabelle az concert","brazzabelle in arizona","brazzabelle maya","featured","maya az","Maya Day &amp; Nightclub","maya dayclub","maya nightclub"],"articleSection":["Artists &amp; Interviews"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/brazzabelle-perform-maya-interview\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/brazzabelle-perform-maya-interview\/","url":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/brazzabelle-perform-maya-interview\/","name":"Brazzabelle to Perform at Maya: Interview","isPartOf":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/brazzabelle-perform-maya-interview\/#primaryimage"},"image":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/brazzabelle-perform-maya-interview\/#primaryimage"},"thumbnailUrl":"https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2014\/06\/27062056\/1480716_10152746498271002_1234820276_n.jpg","datePublished":"2014-06-18T17:35:14+00:00","dateModified":"2014-06-18T20:58:58+00:00","description":"Hot electro music DJ will return to Maya Day + Nightclub on Friday, June 27 at 9 p.m. \u00a0 Brittney Marie Bowles, known for her stage name\u00a0Brazzabelle, is an","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/brazzabelle-perform-maya-interview\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/brazzabelle-perform-maya-interview\/#primaryimage","url":"https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2014\/06\/27062056\/1480716_10152746498271002_1234820276_n.jpg","contentUrl":"https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2014\/06\/27062056\/1480716_10152746498271002_1234820276_n.jpg","width":781,"height":651},{"@type":"WebSite","@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/#website","url":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/","name":"Nightlife","description":"Arizona Nightlife Events, News, Artists and Photos","publisher":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/#organization","name":"AZFoothills.com LLC","url":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/#\/schema\/logo\/image\/","url":"https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2020\/10\/27123536\/apple-touch-icon.jpg","contentUrl":"https:\/\/media.arizonafoothillsmagazine.com\/aznightlife\/wp-content\/uploads\/2020\/10\/27123536\/apple-touch-icon.jpg","width":180,"height":180,"caption":"AZFoothills.com LLC"},"image":{"@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/#\/schema\/person\/f3fd293f90fa601e4a8fa8818beaf4fb","name":"Caitie Andreen","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/01977f29c813ff3684a09aaa2c62964f23e2d8ea10be55b0900c7f9356c28d3d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/01977f29c813ff3684a09aaa2c62964f23e2d8ea10be55b0900c7f9356c28d3d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/01977f29c813ff3684a09aaa2c62964f23e2d8ea10be55b0900c7f9356c28d3d?s=96&d=mm&r=g","caption":"Caitie Andreen"},"url":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/author\/caitie\/"}]}},"_links":{"self":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/wp-json\/wp\/v2\/posts\/26443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/wp-json\/wp\/v2\/comments?post=26443"}],"version-history":[{"count":6,"href":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/wp-json\/wp\/v2\/posts\/26443\/revisions"}],"predecessor-version":[{"id":26451,"href":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/wp-json\/wp\/v2\/posts\/26443\/revisions\/26451"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/wp-json\/wp\/v2\/media\/26444"}],"wp:attachment":[{"href":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/wp-json\/wp\/v2\/media?parent=26443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/wp-json\/wp\/v2\/categories?post=26443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.arizonafoothillsmagazine.com\/aznightlife\/wp-json\/wp\/v2\/tags?post=26443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}